{"id":1375,"date":"2018-04-11T15:16:21","date_gmt":"2018-04-11T15:16:21","guid":{"rendered":"https:\/\/www.finanzen.net\/ratgeber\/boerse\/depotwechsel-einfach-und-kostenlos-tipps-tricks\/"},"modified":"2025-11-11T11:59:05","modified_gmt":"2025-11-11T10:59:05","slug":"depotwechsel","status":"publish","type":"post","link":"https:\/\/www.finanzen.net\/ratgeber\/trading\/praxis-strategien\/depotwechsel\/","title":{"rendered":"Depotwechsel"},"content":{"rendered":"\n<div class=\"container container--narrow\">\n    <div class=\"header\">\n                    <div class=\"header__image\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"882\" src=\"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/shutterstock_2040376241-PhotoRoom.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/shutterstock_2040376241-PhotoRoom.jpg 1920w, https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/shutterstock_2040376241-PhotoRoom-300x138.jpg 300w, https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/shutterstock_2040376241-PhotoRoom-1024x470.jpg 1024w, https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/shutterstock_2040376241-PhotoRoom-768x353.jpg 768w, https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/shutterstock_2040376241-PhotoRoom-1536x706.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>                            <\/div>\n                <div class=\"header__text\">\n                            <div class=\"headline headline--preline headline--h4 header__preline\">\n                    Depot \u00fcbertragen                <\/div>\n                                        <h1 class=\"headline headline--h1 header__headline headline--has-preline\">\n                    Depotwechsel einfach und kostenlos, Tipps &#038; Tricks                <\/h1>\n                        <div class=\"header__excerpt flow-content\">\n                                    <p>Eine der wichtigsten Regeln f\u00fcr Anleger lautet: Geb\u00fchren kosten Rendite! Nur mit einem kosteng\u00fcnstigen Wertpapierdepot kommen Kursgewinne wirklich bei Ihnen an. Ein Depotwechsel kann sich also lohnen. Und das Beste: Ein Depotwechsel ist einfach und kostenlos! In diesem Ratgeber erfahren Sie, wie ein Depot\u00fcbertrag funktioniert und was Sie dabei beachten m\u00fcssen. Gleich zu Beginn gibt&#8217;s die besten Tipps und beantworten wir die wichtigsten Fragen!<\/p>\n                            <\/div>\n            <div class=\"header__footer\">\n                <span class=\"header__meta\">\n                    <img loading=\"lazy\" decoding=\"async\" class=\"header__author-image\"\n                         src=\"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/image-6-150x150.png\"\n                         width=\"58\"\n                         height=\"58\"\n                         alt=\"\">\n                    <span class=\"header__meta-info\">\n                        <span class=\"header__author-name\">\n                            von <a href=\"https:\/\/www.finanzen.net\/ratgeber\/author\/team-ratgeber\/\" title=\"Beitr\u00e4ge von Redaktion Ratgeber\" rel=\"author\" class=\"link link--no-underline\">Redaktion Ratgeber<\/a>                        <\/span>\n                        <span class=\"header__date\">\n                            <span class=\"hide-on-smartphone\">Aktualisiert am<\/span>\n                            <time datetime=\"2025-11-11 11:59\"\n                                  title=\"Aktualisiert am 11.11.2025\">\n                                11.11.25                            <\/time>\n                        <\/span>\n                    <\/span>\n                <\/span>\n\n                                    <div class=\"header__buttons\">\n                                                    <a class=\"fnet-button fnet-button--small\"\n                                                                  style=\"--button-background:#50ce6b;--button-hover-background:#50ce6b;\"\n                                                              href=\"https:\/\/www.finanzen.net\/ratgeber\/rechner-vergleiche\/zinseszinsrechner\/\"\n                               target=\"\">\n                                zum Zinseszinsrechner                            <\/a>\n                                            <\/div>\n                            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow\">\n    <div class=\"box box--type2 box--contrast01 box--small-margin short-info\">\n        <h3 class=\"headline headline--h3 headline--has-icon short-info__headline\" style=\"--headline-icon: url('https:\/\/www.finanzen.net\/ratgeber\/wp-content\/themes\/fnet-ratgeber\/images\/icon-lightbulb-white.svg');\">\n                            Depot-Wechsel &#8211; Das Wichtigste in K\u00fcrze                    <\/h3>\n        <div class=\"box__content\">\n                            <div class=\"flow-content\">\n                    <ul>\n<li>Geb\u00fchren beeinflussen den Anlage-Erfolg ma\u00dfgeblich. Mit einem g\u00fcnstigen Depot senken Sie Geb\u00fchren dauerhaft.<\/li>\n<li>Ein Depotwechsel ist unkompliziert und innerhalb Deutschlands komplett kostenlos. Im <a href=\"https:\/\/www.finanzen.net\/ratgeber\/selection\/online-broker-vergleich\/\" target=\"_blank\" rel=\"noopener\">finanzen.net Online-Broker-Vergleich<\/a> haben wir Banken und Broker miteinander verglichen.<\/li>\n<li>Er\u00f6ffnen Sie bei Ihrem neuen Anbieter ein Wertpapierdepot. F\u00fcr Anleger, die selten handeln, ist die j\u00e4hrliche Grundgeb\u00fchr entscheidend. Bei Vieltradern sind eher die Orderkosten relevant.<\/li>\n<li>Sobald Ihr neues Wertpapierdepot er\u00f6ffnet ist, k\u00f6nnen Sie den Depotwechsel beauftragen: Ihre (noch) aktuelle Bank darf f\u00fcr einzelne Wertpapierposten oder komplette Depots keine gesonderten Geb\u00fchren berechnen.<\/li>\n<li><strong>Hinweis<\/strong>: Der Depot\u00fcbertrag kann einige Tage dauern, w\u00e4hrenddessen sind weder K\u00e4ufe noch Verk\u00e4ufe m\u00f6glich.<\/li>\n<li><strong>Tipp<\/strong>: Ziehen Sie alternativ ein <strong><a href=\"http:\/\/g.finanzen.net\/zero-webmobile-ratgeber-content?utm_content=depotwechsel\" target=\"_blank\" rel=\"noopener\">finanzen.net zero\u00b9<\/a><\/strong> Depot in Betracht. Dort handeln Sie Wertpapiere ohne Ordergeb\u00fchren (zzgl. markt\u00fcblicher Spreads).<\/li>\n<li><strong>Stellen Sie Ihren aktuellen Anbieter auf den Pr\u00fcfstand:<\/strong> Beim Bundesverband der Verbraucherzentralen finden Sie eine <a href=\"https:\/\/www.verbraucherzentrale.de\/sites\/default\/files\/migration_files\/media143251A.pdf\" target=\"_blank\" rel=\"noopener\">Checkliste<\/a>, mit der Sie schnell \u00fcberpr\u00fcfen k\u00f6nnen, ob Ihr Anbieter noch zu Ihnen passt.<\/li>\n<li><strong>Wichtig<\/strong>: Falls Ihre Wertpapiere im Ausland lagern, k\u00f6nnen Kosten bei der neuen Bank entstehen, weil die Bank tats\u00e4chlich anfallende Fremdkosten an den Kunden weiterreichen darf.<\/li>\n<\/ul>\n                <\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow\">\n    <div class=\"box toc\">\n        <h3 class=\"headline headline--h3 headline--has-icon\" style=\"--headline-icon: url('https:\/\/www.finanzen.net\/ratgeber\/wp-content\/themes\/fnet-ratgeber\/images\/icon-list-blue.svg');\">\n                            Inhaltsverzeichnis                    <\/h3>\n        <div class=\"box__content\">\n            <ol class=\"toc__list js-toc-list\">\n                <!-- content generated by toc.js -->\n                            <\/ol>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow js-is-toc\" id=\"Depotwechsel-kann-bares-Geld-wert-sein\" >\n                <h2            class=\"headline headline--h2\"\n                    >\n            Depotwechsel kann bares Geld wert sein        <\/h2>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Schlechter Service, kleines Angebot, Un\u00fcbersichtlichkeit &#8211; Gr\u00fcnde f\u00fcr einen Depotwechsel gibt es viele, mit Abstand am schwersten wiegt aber der Kostenfaktor: Kontof\u00fchrungs\u00adgeb\u00fchren, Depotgeb\u00fchren, Strafzinsen, Ordergeb\u00fchren oder weitere Handelsgeb\u00fchren beeinflussen den Anlageerfolg ganz ma\u00dfgeblich, diese Kosten fallen n\u00e4mlich in guten wie in schlechten B\u00f6rsenzeiten an. Depotf\u00fchrung, Kauf, Verkauf und Verwahrung von Wertpapieren m\u00fcssen bezahlt werden, selbst wenn alle Aktien, ETFs und Zertifikate im Depot an Wert verlieren. Ein Depotwechsel kann also bares Geld wert sein.<\/p>\n<p>Und das Beste: Sie k\u00f6nnen Ihr Wertpapierdepot v\u00f6llig unkompliziert und innerhalb Deutschlands komplett kostenfrei zu einem anderen Anbieter \u00fcbertragen. Zahlreiche Direktbanken bieten kostenlose Wertpapierdepots an, ein Depot\u00fcbertrag ist schnell erledigt. Wir zeigen Ihnen, wie Sie Ihren Depotwechsel Schritt f\u00fcr Schritt vorbereiten und wie Sie dann Ihr Depot kostenlos \u00fcbertragen &#8211; am Ende dieses Ratgebers geben wir Antworten auf die meistgestellten Fragen rund um das Thema <a href=\"#vorteile\">Depot\u00fcbertrag<\/a>.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow js-is-toc\" id=\"Checken-Sie-vor-dem-Depotwechsel-Ihren-Anbieter\" >\n                <h2            class=\"headline headline--h2\"\n                    >\n            Checken Sie vor dem Depotwechsel Ihren Anbieter        <\/h2>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Bevor Sie Ihr Depot wechseln, sollten Sie Ihren bisherigen Anbieter und die Kosten, die mit dem Wertpapierhandel verbunden sind, genau unter die Lupe nehmen. Stellen Sie die Kosten f\u00fcr das Depot dem Nutzen gegen\u00fcber, vergleichen Sie knallhart mit der Konkurrenz und stellen Sie sich unter anderem folgende Fragen: Wie hoch sind die Ordergeb\u00fchren? Passt das Angebot noch zu meiner Anlagestrategie? Bekomme ich Wertpapiere, zum Beispiel <a title=\"Ratgeber ETF-Sparplan\" href=\"https:\/\/www.finanzen.net\/ratgeber\/etf-sparplan\/\" target=\"_blank\" rel=\"noopener\">ETF-Sparpl\u00e4ne<\/a>, kosteng\u00fcnstig? Manchmal kann es sein, dass eine Bank f\u00fcr den Anleger ganz pl\u00f6tzlich nicht mehr geeignet ist, weil dieser seine Anlagestrategie umstellt oder auf andere Wertpapiere setzt. Bei der einen Bank werden volumenabh\u00e4ngige Geb\u00fchren auf Indexfonds erhoben, bei der anderen vielleicht nicht. Bei dem einen Broker kostet der Handel mit US-Aktien doppelt so viel wie bei einem anderen. Die Bank, \u00fcber die Sie handeln, muss also auch immer zu Ihnen und Ihren Zielen passen.<\/p>\n<p>Fakt ist: Zahlreiche Direktbanken bieten ein kostenloses Depot an. F\u00fcr Anleger, die ihre Wertpapiergesch\u00e4fte \u00fcber das Internet abwickeln, sind diese wohl alternativlos. Tipp: Der Bundesverband der Verbraucherzentralen hat eine Checkliste erstellt, mit der Sie schnell und einfach \u00fcberpr\u00fcfen k\u00f6nnen, ob Ihr Wertpapierdepot und Ihr Anbieter noch zu Ihnen als Anleger passen. Die <a title=\"Checkliste Depotwechsel bei der Verbraucherzentrale\" href=\"https:\/\/www.verbraucherzentrale.de\/sites\/default\/files\/migration_files\/media143251A.pdf\" target=\"_blank\" rel=\"noopener\">Checkliste<\/a> k\u00f6nnen Sie hier im PDF-Format abrufen. Eine Faustformel besagt: F\u00fcr Anleger, die selten handeln, ist die j\u00e4hrliche Grundgeb\u00fchr entscheidend, bei Vieltradern sind dagegen eher die Orderkosten relevant.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"box box--type2 box--contrast03 newsletter newsletter--simple\">\n                    <h2                class=\"headline headline--h2 headline--has-icon newsletter__headline\"\n                style=\"--headline-icon: url('https:\/\/www.finanzen.net\/ratgeber\/wp-content\/themes\/fnet-ratgeber\/images\/icon-check-white.svg');\"\n            >\n                Wollen Sie zu aktuellen Empfehlungen rund um das Thema B\u00f6rse auf dem Laufenden bleiben?            <\/h2>\n                <div class=\"box__content box__content--indent\">\n                            <div class=\"flow-content newsletter__text\">\n                    <p>Unser Tipp: Abonnieren Sie jetzt unseren kostenlosen Newsletter!<\/p>\n                <\/div>\n                        <div class=\"fnet-nl-ic__form-area js-fnet-proxy-form-container\">\n              <form class=\"form js-fnet-proxy-form\" name=\"anmelden\" action=\"\" method=\"post\" novalidate>\n                <input type=\"hidden\" class=\"js-fnet-recaptcha-token\" name=\"recaptcha-token\" value=\"\">\n                <input type=\"hidden\" name=\"type\" value=\"Ratgeber\">\n                <input type=\"hidden\" name=\"nl_refurl\" value=\"\">\n                <input type=\"hidden\" name=\"nl_refwidget\" value=\"nl-widget-article-page\">\n                <input type=\"hidden\" name=\"nl_refad\" value=\"\">\n                <input type=\"hidden\" name=\"brandedSignup\" value=\"true\">\n\n                <div class=\"form__fieldset form__fieldset--01\">\n                  <input\n                    class=\"fnet-nl-ic__input\"\n                    id=\"fnet-nl-ic-email\"\n                    type=\"email\"\n                    name=\"email\"\n                    placeholder=\"deine@email.de\"\n                    autocomplete=\"email\"\n                    required\n                  >\n\n                  <p class=\"fnet-nl-ic__error js-fnet-error\"><\/p>\n                  <div class=\"fnet-nl-ic__feedback hidden js-fnet-feedback\" aria-live=\"polite\"><\/div>\n\n                  <div class=\"recaptcha-container\">\n                    <input\n                      class=\"g-recaptcha fnet-nl-ic__btn js-fnet-proxy-submit\"\n                      id=\"fnet-nl-ic-btn\"\n                      data-sitekey=\"6LcBYcoUAAAAAMdyQNuFCMhFBfQUp1jGpohFSA4l\"\n                      data-action=\"newslettersignup\"\n                      name=\"abschicken\"\n                      type=\"button\"\n                      value=\"Jetzt anmelden \u2192\"\n                    >\n                  <\/div>\n                <\/div>\n\n                <small class=\"fnet-nl-ic__legal\">\n                  Informationen zur Verarbeitung deiner personenbezogenen Daten, insbesondere zu Verantwortlichem,\n                  Versanddienstleister, Speicherdauer sowie deinen Rechten, findest du in unserer\n                  <a href=\"https:\/\/www.finanzen.net\/datenschutz\" target=\"_blank\" rel=\"noopener noreferrer\">Datenschutzerkl\u00e4rung<\/a>.\n                <\/small>\n              <\/form>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow js-is-toc\" id=\"Vergleichen-Sie-mit-der-Konkurrenz\" >\n                <h2            class=\"headline headline--h2\"\n                    >\n            Vergleichen Sie mit der Konkurrenz        <\/h2>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Am besten ist es nat\u00fcrlich, wenn Sie sowohl bei Depotgeb\u00fchren als auch bei Orderkosten sparen k\u00f6nnen. Im\u00a0<a title=\"Online-Broker-Vergleich\" href=\"https:\/\/www.finanzen.net\/online-broker-vergleich\/\" target=\"_blank\" rel=\"noopener\">finanzen.net Online-Broker-Vergleich<\/a>\u00a0haben wir die wichtigsten Banken und Broker auf Herz und Nieren gepr\u00fcft und miteinander verglichen. Dabei hat sich unter anderem herausgestellt, dass Orderprovisionen, die unabh\u00e4ngig vom Ordervolumen sind, deutliche Kostenvorteile bringen.<\/p>\n<p><b>Ein Beispiel:<\/b>\u00a0Maxblue, der <a href=\"https:\/\/www.finanzen.net\/ratgeber\/broker\/produkte-vergleiche\/online-broker-vergleich\/\" data-ilm-light=\"95\" title=\"Online Broker Vergleich\">Online-Broker<\/a> der Deutschen Bank, verlangt von seinen Kunden pro Order eine Orderprovision von 0,25\u00a0Prozent des Ordervolumens, mindestens aber 8,90\u00a0Euro. Was zun\u00e4chst wenig klingt, kann sich bei einer Order in einem gr\u00f6\u00dferen Volumen sehr negativ auswirken. F\u00fcr eine Order im Volumen von 10.000\u00a0Euro zahlen Maxblue-Kunden bereits 25,00\u00a0Euro. Mit einem Festpreisangebot w\u00e4re der Anleger deutlich besser gefahren: Als Kunde von\u00a0<a title=\"Online Broker | finanzen.net zero: Depotwechsel ohne Orderkosten\" href=\"http:\/\/g.finanzen.net\/zero-webmobile-ratgeber-content?utm_content=depotwechsel\" target=\"_blank\" rel=\"noopener\"><b>finanzen.net zero<sup>1<\/sup><\/b><\/a>\u00a0zahlen Sie keine Ordergeb\u00fchren, nur Spreads. Eine Order im Volumen von 10.000\u00a0Euro kostet Sie somit ausschlie\u00dflich die markt\u00fcblichen Spreads. In unserem ausf\u00fchrlichen\u00a0<a title=\"Broker Test finanzen.net zero\" href=\"https:\/\/www.finanzen.net\/online-broker-vergleich\/finanzen-net-zero\" target=\"_blank\" rel=\"noopener\">Broker Test finanzen.net zero<\/a>\u00a0haben wir diesen Broker auf Herz und Nieren getestet.<\/p>\n<p>Noch dramatischer kann sich das im Vergleich zwischen einer Direktbank und einer Filialbank darstellen \u2013\u00a0<b>ein weiteres Beispiel:<\/b>\u00a0Kauft ein Anleger Wertpapiere im Wert von 5.000\u00a0Euro, dann kostet ihn das bei der Stadtsparkasse M\u00fcnchen 25\u00a0Euro.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow js-is-toc\" id=\"Kosten-die-Sie-beim-Wertpapierhandel-beachten-mssen\" >\n                <h2            class=\"headline headline--h2\"\n                    >\n            Kosten, die Sie beim Wertpapierhandel beachten m\u00fcssen        <\/h2>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Beim Wertpapierhandel gibt es Kosten, die nicht immer auf den ersten Blick erkennbar sind. Diese k\u00f6nnen sowohl bei Ihrer Hausbank als auch bei einer Direktbank anfallen: Wenn Sie ein Wertpapier kaufen oder verkaufen wollen, dann m\u00fcssen Sie eine sogenannte <b>Ordergeb\u00fchr<\/b> zahlen. Diese verlangt der Depot-Anbieter f\u00fcr die Ausf\u00fchrung Ihres Kauf- oder Verkaufsauftrags. Die <b>B\u00f6rsengeb\u00fchr<\/b> setzt sich aus diversen Kosten zusammen, zum Beispiel Maklercourtage und das Entgelt f\u00fcr den B\u00f6rsenplatz. Manchmal macht die B\u00f6rsengeb\u00fchr bis zu 40 Prozent der gesamten Geb\u00fchren aus. Sie sollten beachten, dass jeder Depotanbieter die B\u00f6rsengeb\u00fchr anders abrechnet. Beim Online-Broker <a href=\"https:\/\/www.finanzen.net\/online-broker-vergleich\/flatex\" target=\"_blank\" rel=\"noopener\">flatex<sup>14<\/sup><\/a> beispielsweise bezahlen Sie f\u00fcr eine Xetra-Order laut Preis-Leistungs-Verzeichnis nur 5,90 Euro (zzgl. markt\u00fcblicher Spreads, Zuwendungen, Produktkosten und Fremdkosten).<\/p>\n<p>Ein Blick in den Passus zu Fremdspesen zeigt jedoch, dass hier weitere Geb\u00fchren hinzukommen, denn eine Xetra-Order schl\u00e4gt mit mindestens 8,27\u00a0Euro zu Buche. Bei <a title=\"Online Broker | finanzen.net zero: Depotwechsel ohne Orderkosten\" href=\"http:\/\/g.finanzen.net\/zero-webmobile-ratgeber-content?utm_content=depotwechsel\" target=\"_blank\" rel=\"noopener\"><b>finanzen.net zero<sup>1<\/sup><\/b><\/a> zahlen Sie keine Ordergeb\u00fchren, nur Spreads. Beide Broker liegen damit weit vorne, wie Sie auch unserem <a href=\"https:\/\/www.finanzen.net\/online-broker-vergleich\/\" target=\"_blank\" rel=\"noopener\">Depot-Vergleich<\/a> entnehmen k\u00f6nnen. Geben Sie <b>Limit Orders<\/b> auf, dann k\u00f6nnen daf\u00fcr Kosten anfallen. Insbesondere dann, wenn die Kauf- oder Verkaufsorder nicht am selben Tag ausgef\u00fchrt wird. Beim Kauf eines Wertpapiers, dessen B\u00f6rsenums\u00e4tze gering sind und dessen Kurse daher stark schwanken k\u00f6nnen, ist es aber dennoch sinnvoll eine Limit Order aufzugeben. So geben Sie beispielsweise einen Kurs (Preis) vor, den Sie h\u00f6chstens bereit sind zu zahlen. Einige Broker und Online-Banken bieten einen au\u00dferb\u00f6rslichen <b>Direkthandel<\/b> an, zum Beispiel \u00fcber die Handelspl\u00e4tze Tradegate oder Lang &amp; Schwarz. Die B\u00f6rsengeb\u00fchr entf\u00e4llt in diesem Fall.<\/p>\n<p>Beim Direkthandel handeln Anleger nicht \u00fcber eine B\u00f6rse, sondern mit einer Bank oder einem Wertpapierhaus. Die Bank oder der Broker kaufen die Wertpapiere an und verkaufen diese auch wieder. In der Regel wissen Anleger beim Direkthandel vorher ganz genau, was eine Order kostet. <b>Bid-ask-spread<\/b> ist die Differenz zwischen Geldkurs und Briefkurs, die vergleichbar mit einer Maklergeb\u00fchr ist. Bei Aktien und ETFs, die viel und in gro\u00dfem Umfang gehandelt werden, betr\u00e4gt der Bid-ask-spread weniger als 0,1\u00a0Prozent. Bei selten gehandelten Wertpapieren kann diese &#8222;Maklergeb\u00fchr&#8220; oftmals mehrere Prozent betragen. Die Differenz zwischen Geldkurs und Briefkurs ist au\u00dferhalb der B\u00f6rsenzeiten deutlich gr\u00f6\u00dfer, entscheidend f\u00fcr die H\u00f6he der Geb\u00fchr sind immer die \u00d6ffnungszeiten der Heimatb\u00f6rse eines Wertpapiers. Wichtig: Sie sollten Angebote und Kosten vergleichen, die f\u00fcr Sie auch dauerhaft wichtig sind und Ihnen im Idealfall auf lange Sicht Vorteile sichern. Machen Sie keinen Depotwechsel nur wegen einer zeitlich begrenzten Aktion, wechseln Sie also nicht den Anbieter nur wegen eines aktuellen Pr\u00e4mienangebots.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow \" >\n    <div class=\"highlightbox-container\">\n                    <div class=\"highlightbox box\">\n                                    <h3                        class=\"headline headline--h3 headline--has-icon\"\n                                                    style=\"--headline-icon: url('https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2023\/10\/icon-lightbulb.svg');\"\n                                            >\n                        Kosten beim Wertpapierhandel &#8211; darauf m\u00fcssen Sie achten!                    <\/h3>\n                                <div class=\"box__content\">\n                                            <div class=\"flow-content\">\n                            <ul>\n<li class=\"listing-text\">Ordergeb\u00fchren<\/li>\n<li class=\"listing-text\">B\u00f6rsengeb\u00fchren<\/li>\n<li class=\"listing-text\">Kosten bei Limit Orders<\/li>\n<li class=\"listing-text\">Bid-ask-spread (&#8222;Maklergeb\u00fchr&#8220;)<\/li>\n<\/ul>\n                        <\/div>\n                                                        <\/div>\n            <\/div>\n            <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow js-is-toc\" id=\"Vor-dem-Depotbertrag-Neues-Wertpapierdepot-erffnen\" >\n                <h2            class=\"headline headline--h2\"\n                    >\n            Vor dem Depot\u00fcbertrag: Neues Wertpapierdepot er\u00f6ffnen        <\/h2>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Haben Sie die Angebote ausreichend verglichen, einen neuen (und f\u00fcr Sie pers\u00f6nlich passenden) Anbieter ausgemacht und sich zum Depotwechsel entschieden? Dann er\u00f6ffnen Sie im n\u00e4chsten Schritt ein Wertpapierdepot bei Ihrer neuen Bank oder Ihrem neuen Online-Broker. Es muss schlie\u00dflich ein neues Wertpapierdepot existieren, bevor Sie den Depot\u00fcbertrag in Auftrag geben k\u00f6nnen.<\/p>\n<p>Wollen Sie Ihr neues Depot bei einer Filialbank er\u00f6ffnen, dann erledigt Ihr Bankberater dies f\u00fcr Sie. Bei einer Direktbank oder einem Onlinebroker m\u00fcssen Sie sich in der Regel \u00fcber das sogenannte \u201ePostIdent\u201c-Verfahren zweifelsfrei identifizieren. Laden Sie in diesem Fall auf der Internetseite Ihres Anbieters den Antrag \u201eWertpapierdepot er\u00f6ffnen\u201c sowie das von der Bank bereitgestellte Formular zum \u201ePostIdent\u201c-Verfahren herunter \u2013 f\u00fcllen Sie beide Formulare aus und befolgen Sie die weiteren Schritte. Einige Internetbanken bieten mittlerweile \u00fcbrigens auch das \u201eVideoIdent\u201c-Verfahren an, mit dem Sie per Videoschaltung den Antrag er\u00f6ffnen k\u00f6nnen.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"youtube-channel-teaser box\">\n                    <a class=\"youtube-channel-teaser__image-container\" href=\"https:\/\/www.youtube.com\/channel\/UCxD5ug_M184KrXgPj9v7qeA\" target=\"_blank\">\n                <img decoding=\"async\" src=\"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2023\/10\/icon-youtube.svg\">\n            <\/a>\n                            <div class=\"box__content flow-content\">\n                <p><strong>Du willst noch mehr Finanzwissen schnell erkl\u00e4rt?<\/strong><br \/>\n<a href=\"https:\/\/www.youtube.com\/channel\/UCxD5ug_M184KrXgPj9v7qeA\" target=\"_blank\" rel=\"noopener\">Dann abonniere jetzt unseren YouTube-Kanal!<\/a> Wir produzieren regelm\u00e4\u00dfig neue <strong>Ratgeber-Videos<\/strong> rund um die Themen B\u00f6rse, <a href=\"https:\/\/www.finanzen.net\/ratgeber\/trading\/grundlagen-einstieg\/geldanlage\/\" data-ilm-light=\"32\" title=\"Geldanlage\">Geldanlage<\/a> und Finanzen. Als Abonnent wirst du sofort informiert, wenn ein neues Erkl\u00e4rvideo erscheint &#8211; so verpasst du nichts mehr!<\/p>\n            <\/div>\n            <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow js-is-toc\" id=\"So-funktioniert-der-Depotwechsel\" >\n                <h2            class=\"headline headline--h2\"\n                    >\n            So funktioniert der Depotwechsel        <\/h2>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Sobald Ihr neues Wertpapierdepot er\u00f6ffnet ist, k\u00f6nnen Sie den Depot\u00fcbertrag beauftragen. Innerhalb Deutschlands ist ein Depotwechsel kostenlos. Der Bundesgerichtshof (BGH) hat in zwei Urteilen (Az. XI ZR 200\/03 und Az. XI ZR 49\/04) entschieden, dass Kreditinstitute keine gesonderten Geb\u00fchren beim Depot\u00fcbertrag berechnen d\u00fcrfen: Ihre (noch) aktuelle Bank darf f\u00fcr den \u00dcbertrag einzelner Wertpapierposten oder kompletter Depots keine gesonderten Geb\u00fchren berechnen.<\/p>\n<p>Einige Geldinstitute bieten einen Service f\u00fcr den Depotumzug an und nehmen so ihren Kunden einen Gro\u00dfteil der Arbeit ab. Sie m\u00fcssen dann lediglich ein Formular ausf\u00fcllen, das Ihre neue Bank erm\u00e4chtigt, die Wertpapiere Ihres \u201ealten\u201c Depots zu \u00fcbertragen. Wenn Sie wollen, k\u00f6nnen auch nur einzelne Aktien, Fonds oder ETFs f\u00fcr einen \u00dcbertrag ausw\u00e4hlen. Den Rest erledigen die Banken in der Regel unter sich. Nat\u00fcrlich k\u00f6nnen Sie den \u00dcbertrag der Wertpapiere auch pers\u00f6nlich bei Ihrem alten Anbieter veranlassen.<\/p>\n<p>In Deutschland ans\u00e4ssige Banken sind zur Weitergabe der Anschaffungsdaten (Kaufdatum und Kaufkurs) gesetzlich verpflichtet. Erfolgt keine \u00dcbermittlung, weil die depotf\u00fchrende Bank beispielsweise Ihren Sitz im Ausland hat, dann werden die \u00fcbertragenen Papiere als \u201eNeuf\u00e4lle\u201c betrachtet und pauschal versteuert. Sie m\u00fcssen dann die anfallenden Steuern in der Einkommenssteuererkl\u00e4rung geltend machen. Diesen B\u00fcrokratieaufwand k\u00f6nnen Sie sich sparen, wenn Sie sich direkt von Ihrem alten Anbieter best\u00e4tigen lassen, dass die Anschaffungsdaten beim Depotwechsel vollst\u00e4ndig an den neuen Broker oder die neue Bank \u00fcbermittelt werden.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow \" >\n    <div class=\"highlightbox-container\">\n                    <div class=\"highlightbox box\">\n                                    <h3                        class=\"headline headline--h3 headline--has-icon\"\n                                                    style=\"--headline-icon: url('https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2023\/10\/icon-question-dark.svg');\"\n                                            >\n                        Clearstream und Wertpapiere im Ausland &#8211; schon gewusst?                    <\/h3>\n                                <div class=\"box__content\">\n                                            <div class=\"flow-content\">\n                            <p>Falls Ihre Wertpapiere im Ausland lagern oder nicht via Clearstream verwahrt werden, dann k\u00f6nnen Kosten bei der neuen Bank entstehen, denn: Tats\u00e4chlich anfallende Fremdkosten darf die Bank aber an den Kunden weiterreichen.<\/p>\n<p>Clearstream ist \u00fcbrigens ein &#8222;Zentralverwahrer&#8220;, der als Schnittstelle zwischen verschiedenen Online-Brokern dient.<\/p>\n                        <\/div>\n                                                        <\/div>\n            <\/div>\n            <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow\" >\n                <h2            class=\"headline headline--h2\"\n                    >\n            K\u00fcndigen Sie nach dem Depotwechsel das &#8222;alte&#8220; Depot!        <\/h2>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Ist der Depot\u00fcbertrag erfolgreich abgeschlossen und alle Ihre Wertpapiere sind wohlbehalten auf dem neuen Depot angekommen? Dann sollten Sie das \u201ealte\u201c Depot bei Ihrem bisherigen Anbieter schriftlich k\u00fcndigen und aufl\u00f6sen (die Vorteile nur eines einzigen Wertpapierdepots erl\u00e4utern wir Ihnen unter\u00a0<a href=\"#vorteile\">meistgestellte Fragen<\/a>.<\/p>\n<p>Sind noch Bruchst\u00fccke von Fondsanteilen auf Ihrem bisherigen Wertpapierdepot vorhanden, dann m\u00fcssen Sie diese vor der K\u00fcndigung noch verkaufen. In der Regel verkauft Ihre depotf\u00fchrende Bank diese Anteilsbruchst\u00fccke und \u00fcberweist den Erl\u00f6s auf Ihr Referenz- bzw. Verrechnungskonto, manchmal nimmt Ihnen Ihr neuer Anbieter diesen Verkauf ab.<\/p>\n<p>Welche Fristen Sie bei der K\u00fcndigung Ihres alten Depots beachten m\u00fcssen, entnehmen Sie bitte Ihrem Depotvertrag.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow \" >\n    <div class=\"highlightbox-container\">\n                    <div class=\"highlightbox box\">\n                                    <h3                        class=\"headline headline--h3 headline--has-icon\"\n                                                    style=\"--headline-icon: url('https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2023\/10\/icon-lightbulb.svg');\"\n                                            >\n                        So sparen Sie weitere Geb\u00fchren bei der Geldanlage                    <\/h3>\n                                <div class=\"box__content\">\n                                            <div class=\"flow-content\">\n                            <p>Eine der wichtigsten Regeln f\u00fcr Anleger lautet, wie gesagt, Geb\u00fchren kosten Rendite! Mit einem Depotwechsel hin zu einem g\u00fcnstigeren Anbieter schaffen Sie die besten Voraussetzungen, diese dauerhaft zu reduzieren. Wie Sie dar\u00fcber hinaus Ihre Finanzen in den Griff bekommen und die Ertr\u00e4ge weiter optimieren k\u00f6nnen, haben wir in unserem\u00a0<a title=\"7 Tipps zur Geldananlage\" href=\"https:\/\/www.finanzen.net\/ratgeber\/geldanlage\/\" target=\"_blank\" rel=\"noopener\">Ratgeber Geldanlage<\/a>\u00a0f\u00fcr Sie zusammengefasst.<\/p>\n<p><strong><span class=\"lightbulb-text\">Unsere Empfehlung:<\/span><\/strong>\u00a0Suchen Sie sich einen g\u00fcnstigen Onlinebroker, wie\u00a0<a title=\"Online Broker | finanzen.net zero: Depotwechsel ohne Orderkosten\" href=\"http:\/\/g.finanzen.net\/zero-webmobile-ratgeber-content?utm_content=depotwechsel\" target=\"_blank\" rel=\"noopener\"><b>finanzen.net zero<sup>1<\/sup><\/b><\/a>, und passen Sie Ihre Geldanlage an Ihre Bed\u00fcrfnisse m\u00f6glichst kosteng\u00fcnstig an. Mit einem g\u00fcnstigen\u00a0<a title=\"Ratgeber ETF-Sparplan\" href=\"https:\/\/www.finanzen.net\/ratgeber\/etf-sparplan\/\">ETF-Sparplan<\/a>\u00a0k\u00f6nnen Sie zum Beispiel langfristig ein kleines Verm\u00f6gen aufbauen, kurzfristig passt m\u00f6glicherweise ein\u00a0<a title=\"Ratgeber Tagesgeldvergleich\" href=\"https:\/\/www.finanzen.net\/ratgeber\/tagesgeld-vergleich\/\" target=\"_blank\" rel=\"noopener\">Tagesgeldkonto<\/a>\u00a0zu Ihren Zielen.<\/p>\n                        <\/div>\n                                                        <\/div>\n            <\/div>\n            <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow js-is-toc\" id=\"Depotwechsel-Die-meistgestellten-Fragen\" >\n                <h2            class=\"headline headline--h2\"\n                    >\n            Depotwechsel: Die meistgestellten Fragen        <\/h2>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" id=\"vorteile\" >\n                <h3            class=\"headline headline--h3\"\n                    >\n            Welche Vorteile hat ein Depotwechsel?        <\/h3>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Durch einen Depotwechsel sparen Sie sich unn\u00f6tigen Verwaltungsaufwand \u2013 und m\u00f6glicherweise unn\u00f6tige Kosten. Depot- oder Verwahrgeb\u00fchren bei Ihrem alten Anbieter k\u00f6nnen Sie sich durch einen Umzug Ihres Depots sparen. Nutzen Sie nur ein einziges Wertpapierdepot, dann haben Sie es auch bei der Abwicklung Ihrer Steuererkl\u00e4rung leichter.<\/p>\n<p>Au\u00dferdem k\u00f6nnen Sie die Entwicklung Ihres Wertpapierbestandes einfacher verfolgen; Gewinne auf dem einen Depot m\u00fcssen Sie beispielsweise nicht mit Verlusten auf dem anderen Depot gegenrechnen. Nach dem Depot\u00fcbertrag haben Sie nur noch einen Ansprechpartner, der Sie \u00fcber alles rund um Ihre Wertpapiere informiert.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow\" >\n                <h3            class=\"headline headline--h3\"\n                    >\n            Was muss ich bei einem Depot\u00fcbertrag beachten?        <\/h3>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Bedenken Sie, dass der \u00dcbertrag der Wertpapiere einige Tage bis einige Wochen dauern kann. In dieser Zeit k\u00f6nnen Sie nicht \u00fcber die \u00fcbertragenen Wertpapiere verf\u00fcgen. W\u00e4hrend des Depot\u00fcbertrags sind also weder K\u00e4ufe noch Verk\u00e4ufe m\u00f6glich.<\/p>\n<p><strong><span class=\"lightbulb-text\">Tipp:<\/span><\/strong>\u00a0F\u00fchren Sie nur dann einen Depotwechsel durch, wenn die B\u00f6rsen ruhig sind und wenn keine Ereignisse anstehen, die die M\u00e4rkte durcheinanderbringen k\u00f6nnten. \u00dcbertragen Sie Ihr Depot also nicht, wenn eine richtungsweisende Wahl oder eine tiefgreifende politische Entscheidung ansteht.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow\" >\n                <h3            class=\"headline headline--h3\"\n                    >\n            Wie lange dauert ein Depot\u00fcbertrag?        <\/h3>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Ein Depot\u00fcbertrag ist schnell in Gang gebracht: Senden Sie, wie weiter oben beschrieben, einfach das vollst\u00e4ndig ausgef\u00fcllte und unterschriebene Formular \u201eDepot\u00fcbertrag\u201c an Ihre bisherige Bank. Von dort werden dann Ihre Wertpapiere zu Ihrem neuen Anbieter innerhalb von ein bis zwei Wochen kostenlos \u00fcbertragen. Die Bearbeitungsdauer h\u00e4ngt aber ma\u00dfgeblich von der \u00fcbergebenden Bank ab, vor allem bei ausl\u00e4ndischen Banken kann es zu Verz\u00f6gerungen kommen.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow\" >\n                <h3            class=\"headline headline--h3\"\n                    >\n            Muss ich mein bisheriges Depot nach einem Depotwechsel k\u00fcndigen?        <\/h3>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Ja, Sie m\u00fcssen Ihr Depot bei Ihrem bisherigen Anbieter k\u00fcndigen. Das &#8222;alte&#8220; Depot wird nur auf Ihren ausdr\u00fccklichen Wunsch hin aufgel\u00f6st. Wie bereits weiter oben erw\u00e4hnt, hat es (zum Beispiel steuerliche) <a href=\"#vorteile\">Vorteile<\/a>, wenn Sie auch in Zukunft nur ein Wertpapierdepot im Blick haben m\u00fcssen.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow js-is-toc\" id=\"Depot-bertragen--das-sollten-Sie-tun\" >\n                <h2            class=\"headline headline--h2\"\n                    >\n            Depot \u00fcbertragen &#8211; das sollten Sie tun        <\/h2>\n        <\/div>\n\n\n\n<div class=\"container container--narrow \" >\n            <ol class=\"ordered-list ordered-list--type1\">\n                           <li class=\"ordered-list__item\">\n                    <div class=\"ordered-list__content\">\n                                                                            <div class=\"ordered-list__text\">\n                                <p>Geb\u00fchren beeinflussen ma\u00dfgeblich Ihren Anlageerfolg. Wer ein g\u00fcnstiges Depot w\u00e4hlt, senkt dauerhaft die Kosten.<\/p>\n                            <\/div>\n                                            <\/div>\n                <\/li>\n                            <li class=\"ordered-list__item\">\n                    <div class=\"ordered-list__content\">\n                                                                            <div class=\"ordered-list__text\">\n                                <p>Wer noch kein Depot hat, sollte vor einer Entscheidung die Angebote auf der Grundlage unserer Tipps vergleichen.<\/p>\n                            <\/div>\n                                            <\/div>\n                <\/li>\n                            <li class=\"ordered-list__item\">\n                    <div class=\"ordered-list__content\">\n                                                                            <div class=\"ordered-list__text\">\n                                <p>Sie haben bereits ein Depot? Stellen Sie Ihren aktuellen Anbieter auf den Pr\u00fcfstand.<\/p>\n                            <\/div>\n                                            <\/div>\n                <\/li>\n                            <li class=\"ordered-list__item\">\n                    <div class=\"ordered-list__content\">\n                                                                            <div class=\"ordered-list__text\">\n                                <p>Erst wenn Sie ein neues Wertpapierdepot er\u00f6ffnet haben, ist ein Depot\u00fcbertrag m\u00f6glich.<\/p>\n                            <\/div>\n                                            <\/div>\n                <\/li>\n                            <li class=\"ordered-list__item\">\n                    <div class=\"ordered-list__content\">\n                                                                            <div class=\"ordered-list__text\">\n                                <p>F\u00fchren Sie einen Depotwechsel nur durch, wenn die B\u00f6rsen ruhig sind. Denn der Depot\u00fcbertrag kann einige Tage dauern und w\u00e4hrenddessen sind keine K\u00e4ufe und Verk\u00e4ufe m\u00f6glich.<\/p>\n                            <\/div>\n                                            <\/div>\n                <\/li>\n                    <\/ol>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Eine der wichtigsten Regeln f\u00fcr Anleger lautet: Geb\u00fchren kosten Rendite! Nur mit einem kosteng\u00fcnstigen Wertpapierdepot kommen Kursgewinne wirklich bei Ihnen an. Ein Depotwechsel kann sich also lohnen. Und das Beste: Ein Depotwechsel ist einfach und kostenlos! In diesem Ratgeber erfahren Sie, wie ein Depot\u00fcbertrag funktioniert und was Sie dabei beachten m\u00fcssen. Gleich zu Beginn gibt&#8217;s die besten Tipps und beantworten wir die wichtigsten Fragen!<\/p>\n","protected":false},"author":16,"featured_media":3853,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1435],"tags":[],"class_list":["post-1375","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-praxis-strategien"],"acf":[],"yoast_head":"<title>Depotwechsel einfach und kostenlos, Tipps &amp; Tricks | finanzen.net<\/title>\n<meta name=\"description\" content=\"Ratgeber: Mit einem kostenlosen Depotwechsel sparen Sie bares Geld - darauf m\u00fcssen Sie achten und so funktioniert der Depot\u00fcbertrag.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.finanzen.net\/ratgeber\/trading\/praxis-strategien\/depotwechsel\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Depotwechsel einfach und kostenlos, Tipps &amp; Tricks | finanzen.net\" \/>\n<meta property=\"og:description\" content=\"Ratgeber: Mit einem kostenlosen Depotwechsel sparen Sie bares Geld - darauf m\u00fcssen Sie achten und so funktioniert der Depot\u00fcbertrag.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.finanzen.net\/ratgeber\/trading\/praxis-strategien\/depotwechsel\/\" \/>\n<meta property=\"og:site_name\" content=\"Finanzen.net Ratgeber: Finanzwissen, das dich weiterbringt\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-11T15:16:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-11T10:59:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/shutterstock_2040376241-PhotoRoom.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"882\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redaktion Ratgeber\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redaktion Ratgeber\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>","yoast_head_json":{"title":"Depotwechsel einfach und kostenlos, Tipps & Tricks | finanzen.net","description":"Ratgeber: Mit einem kostenlosen Depotwechsel sparen Sie bares Geld - darauf m\u00fcssen Sie achten und so funktioniert der Depot\u00fcbertrag.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.finanzen.net\/ratgeber\/trading\/praxis-strategien\/depotwechsel\/","og_locale":"de_DE","og_type":"article","og_title":"Depotwechsel einfach und kostenlos, Tipps & Tricks | finanzen.net","og_description":"Ratgeber: Mit einem kostenlosen Depotwechsel sparen Sie bares Geld - darauf m\u00fcssen Sie achten und so funktioniert der Depot\u00fcbertrag.","og_url":"https:\/\/www.finanzen.net\/ratgeber\/trading\/praxis-strategien\/depotwechsel\/","og_site_name":"Finanzen.net Ratgeber: Finanzwissen, das dich weiterbringt","article_published_time":"2018-04-11T15:16:21+00:00","article_modified_time":"2025-11-11T10:59:05+00:00","og_image":[{"width":1920,"height":882,"url":"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/shutterstock_2040376241-PhotoRoom.jpg","type":"image\/jpeg"}],"author":"Redaktion Ratgeber","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"Redaktion Ratgeber","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.finanzen.net\/ratgeber\/trading\/praxis-strategien\/depotwechsel\/#article","isPartOf":{"@id":"https:\/\/www.finanzen.net\/ratgeber\/trading\/praxis-strategien\/depotwechsel\/"},"author":{"name":"Redaktion Ratgeber","@id":"https:\/\/www.finanzen.net\/ratgeber\/#\/schema\/person\/7de2b54939f007854918b2e05989b109"},"headline":"Depotwechsel","datePublished":"2018-04-11T15:16:21+00:00","dateModified":"2025-11-11T10:59:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.finanzen.net\/ratgeber\/trading\/praxis-strategien\/depotwechsel\/"},"wordCount":2618,"image":{"@id":"https:\/\/www.finanzen.net\/ratgeber\/trading\/praxis-strategien\/depotwechsel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/shutterstock_2040376241-PhotoRoom.jpg","articleSection":["Praxis &amp; Strategien"],"inLanguage":"de"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.finanzen.net\/ratgeber\/trading\/praxis-strategien\/depotwechsel\/","url":"https:\/\/www.finanzen.net\/ratgeber\/trading\/praxis-strategien\/depotwechsel\/","name":"Depotwechsel einfach und kostenlos, Tipps & Tricks | finanzen.net","isPartOf":{"@id":"https:\/\/www.finanzen.net\/ratgeber\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.finanzen.net\/ratgeber\/trading\/praxis-strategien\/depotwechsel\/#primaryimage"},"image":{"@id":"https:\/\/www.finanzen.net\/ratgeber\/trading\/praxis-strategien\/depotwechsel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/shutterstock_2040376241-PhotoRoom.jpg","datePublished":"2018-04-11T15:16:21+00:00","dateModified":"2025-11-11T10:59:05+00:00","author":{"@id":"https:\/\/www.finanzen.net\/ratgeber\/#\/schema\/person\/7de2b54939f007854918b2e05989b109"},"description":"Ratgeber: Mit einem kostenlosen Depotwechsel sparen Sie bares Geld - darauf m\u00fcssen Sie achten und so funktioniert der Depot\u00fcbertrag.","breadcrumb":{"@id":"https:\/\/www.finanzen.net\/ratgeber\/trading\/praxis-strategien\/depotwechsel\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.finanzen.net\/ratgeber\/trading\/praxis-strategien\/depotwechsel\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.finanzen.net\/ratgeber\/trading\/praxis-strategien\/depotwechsel\/#primaryimage","url":"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/shutterstock_2040376241-PhotoRoom.jpg","contentUrl":"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/shutterstock_2040376241-PhotoRoom.jpg","width":1920,"height":882},{"@type":"BreadcrumbList","@id":"https:\/\/www.finanzen.net\/ratgeber\/trading\/praxis-strategien\/depotwechsel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.finanzen.net\/ratgeber\/"},{"@type":"ListItem","position":2,"name":"Aktien","item":"https:\/\/www.finanzen.net\/ratgeber\/.\/aktien\/"},{"@type":"ListItem","position":3,"name":"Depotwechsel"}]},{"@type":"WebSite","@id":"https:\/\/www.finanzen.net\/ratgeber\/#website","url":"https:\/\/www.finanzen.net\/ratgeber\/","name":"Finanzen.net Ratgeber - Die Ganze Welt der Finanzen","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.finanzen.net\/ratgeber\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.finanzen.net\/ratgeber\/#\/schema\/person\/7de2b54939f007854918b2e05989b109","name":"Redaktion Ratgeber","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/image-6-150x150.png","url":"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/image-6-150x150.png","contentUrl":"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/image-6-150x150.png","caption":"Redaktion Ratgeber"},"url":"https:\/\/www.finanzen.net\/ratgeber\/author\/team-ratgeber\/"}]}},"_links":{"self":[{"href":"https:\/\/www.finanzen.net\/ratgeber\/wp-json\/wp\/v2\/posts\/1375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.finanzen.net\/ratgeber\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.finanzen.net\/ratgeber\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.finanzen.net\/ratgeber\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.finanzen.net\/ratgeber\/wp-json\/wp\/v2\/comments?post=1375"}],"version-history":[{"count":5,"href":"https:\/\/www.finanzen.net\/ratgeber\/wp-json\/wp\/v2\/posts\/1375\/revisions"}],"predecessor-version":[{"id":21273,"href":"https:\/\/www.finanzen.net\/ratgeber\/wp-json\/wp\/v2\/posts\/1375\/revisions\/21273"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.finanzen.net\/ratgeber\/wp-json\/wp\/v2\/media\/3853"}],"wp:attachment":[{"href":"https:\/\/www.finanzen.net\/ratgeber\/wp-json\/wp\/v2\/media?parent=1375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.finanzen.net\/ratgeber\/wp-json\/wp\/v2\/categories?post=1375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.finanzen.net\/ratgeber\/wp-json\/wp\/v2\/tags?post=1375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}