{"id":1495,"date":"2018-11-29T17:17:44","date_gmt":"2018-11-29T16:17:44","guid":{"rendered":"https:\/\/www.finanzen.net\/ratgeber\/boerse\/duesseldorfer-tabelle-2023-so-viel-unterhalt-steht-scheidungskindern-zu-die-aktuelle-unterhaltstabelle\/"},"modified":"2025-11-11T16:07:50","modified_gmt":"2025-11-11T15:07:50","slug":"duesseldorfer-tabelle-kindesunterhalt","status":"publish","type":"post","link":"https:\/\/www.finanzen.net\/ratgeber\/allgemein\/duesseldorfer-tabelle-kindesunterhalt\/","title":{"rendered":"D\u00fcsseldorfer Tabelle 2025"},"content":{"rendered":"\n<div class=\"container container--narrow\">\n    <div class=\"header\">\n                    <div class=\"header__image\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1152\" src=\"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2018\/11\/R2.0_Duesseldorfer_Tabelle.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2018\/11\/R2.0_Duesseldorfer_Tabelle.jpg 1920w, https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2018\/11\/R2.0_Duesseldorfer_Tabelle-300x180.jpg 300w, https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2018\/11\/R2.0_Duesseldorfer_Tabelle-1024x614.jpg 1024w, https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2018\/11\/R2.0_Duesseldorfer_Tabelle-768x461.jpg 768w, https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2018\/11\/R2.0_Duesseldorfer_Tabelle-1536x922.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>                            <\/div>\n                <div class=\"header__text\">\n                            <div class=\"headline headline--preline headline--h4 header__preline\">\n                    Kindesunterhalt                <\/div>\n                                        <h1 class=\"headline headline--h1 header__headline headline--has-preline\">\n                    D\u00fcsseldorfer Tabelle 2025: So viel Unterhalt steht Scheidungskindern zu &#8211; die aktuelle Unterhaltstabelle                <\/h1>\n                        <div class=\"header__excerpt flow-content\">\n                                    <p>Die D\u00fcsseldorfer Tabelle verr\u00e4t, wie viel Unterhalt Scheidungskinder erhalten. Wie die aktuelle Unterhaltstabelle zeigt, stehen unter Umst\u00e4nden auch vollj\u00e4hrigen Kindern Zahlungen zu. In unserem Artikel zur D\u00fcsseldorfer Tabelle 2025 verraten wir, wie hoch der Kindesunterhalt aktuell ist und was Sie als Eltern tun m\u00fcssen. Gleich zu Beginn gibt&#8217;s die besten Tipps und beantworten wir die wichtigsten Fragen!<\/p>\n                            <\/div>\n            <div class=\"header__footer\">\n                <span class=\"header__meta\">\n                    <img loading=\"lazy\" decoding=\"async\" class=\"header__author-image\"\n                         src=\"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/image-6-150x150.png\"\n                         width=\"58\"\n                         height=\"58\"\n                         alt=\"\">\n                    <span class=\"header__meta-info\">\n                        <span class=\"header__author-name\">\n                            von <a href=\"https:\/\/www.finanzen.net\/ratgeber\/author\/team-ratgeber\/\" rel=\"author\" class=\"link link--no-underline\">Redaktion Ratgeber<\/a>                        <\/span>\n                        <span class=\"header__date\">\n                            <span class=\"hide-on-smartphone\">Aktualisiert am<\/span>\n                            <time datetime=\"2025-11-11 16:07\"\n                                  title=\"Aktualisiert am 11.11.2025\">\n                                11.11.25                            <\/time>\n                        <\/span>\n                    <\/span>\n                <\/span>\n\n                            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow\">\n    <div class=\"box box--type2 box--contrast01 box--small-margin short-info\">\n        <h3 class=\"headline headline--h3 headline--has-icon short-info__headline\" style=\"--headline-icon: url('https:\/\/www.finanzen.net\/ratgeber\/wp-content\/themes\/fnet-ratgeber\/images\/icon-lightbulb-white.svg');\">\n                            D\u00fcsseldorfer Tabelle 2025 &#8211; Das Wichtigste in K\u00fcrze                    <\/h3>\n        <div class=\"box__content\">\n                            <div class=\"flow-content\">\n                    <ul>\n<li>Der Mindestunterhalt f\u00fcr minderj\u00e4hrige Kinder richtet sich nach dem Existenzminimum des Kindes und der Mindestunterhaltsverordnung.<\/li>\n<li>Der Mindestunterhalt minderj\u00e4hriger Kinder betr\u00e4gt dann ab dem 1. Januar bis zur Vollendung des 6. Lebensjahres (1. Altersstufe) 482 statt bisher 480 Euro, f\u00fcr die Zeit vom 7. bis zur Vollendung des 12. Lebensjahres (2. Altersstufe) 554 statt bisher 551 Euro und f\u00fcr die Zeit vom 13. Lebensjahr bis zur Vollj\u00e4hrigkeit (3. Altersstufe) 649 statt bisher 645 Euro monatlich.<\/li>\n<li>Um Familien zu unterst\u00fctzen, betr\u00e4gt das Kindergeld im Jahr 2025 255 Euro. Diese <a href=\"#duesseldorfer-tabelle-kindesunterhalt\">Zahlbetr\u00e4ge f\u00fcr den Unterhalt<\/a> ergeben sich nach Abzug des Kindergeldes f\u00fcr Sie.<\/li>\n<li>Die D\u00fcsseldorfer Tabelle regelt die H\u00f6he von Unterhaltszahlungen und wird normalerweise j\u00e4hrlich aktualisiert. Ziel der D\u00fcsseldorfer Tabelle ist es, die Rechtsprechung der Familiengerichte unter anderem bez\u00fcglich des Kindesunterhalts zu standardisieren. &#8222;Unterhalt&#8220; sichert den Lebensbedarf einer Person &#8211; vollst\u00e4ndig oder zumindest teilweise.<\/li>\n<li>Ziel der D\u00fcsseldorfer Tabelle ist es, die Rechtsprechung der Familiengerichte unter anderem bez\u00fcglich des Kindesunterhalts zu standardisieren.<\/li>\n<li>\n<div class=\"listing-text\">&#8222;Unterhalt&#8220; sichert den Lebensbedarf einer Person\u00a0&#8211; vollst\u00e4ndig oder zumindest teilweise.<\/div>\n<\/li>\n<\/ul>\n                <\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow\">\n    <div class=\"box toc\">\n        <h3 class=\"headline headline--h3 headline--has-icon\" style=\"--headline-icon: url('https:\/\/www.finanzen.net\/ratgeber\/wp-content\/themes\/fnet-ratgeber\/images\/icon-list-blue.svg');\">\n                            Inhaltsverzeichnis\n                    <\/h3>\n        <div class=\"box__content\">\n            <ol class=\"toc__list js-toc-list\">\n                <!-- content generated by toc.js -->\n                            <\/ol>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow js-is-toc\" id=\"Was-ist-die-Dsseldorfer-Tabelle\" >\n                <h2            class=\"headline headline--h2\"\n                    >\n            Was ist die D\u00fcsseldorfer Tabelle?        <\/h2>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Wer nach einer Scheidung wissen m\u00f6chte, wie viel Unterhalt die gemeinsamen Kinder erhalten, muss einen Blick in die sogenannte D\u00fcsseldorfer Tabelle werfen. Diese Unterhaltstabelle gibt Auskunft dar\u00fcber, welche Zahlungen Sie leisten m\u00fcssen oder, wenn die Kinder bei Ihnen leben, welchen Unterhalt die Kinder von Ihrem (Ex-)Partner bekommen.<\/p>\n<p>Die D\u00fcsseldorfer Tabelle ist eine bundesweit anerkannte Richtlinie zum Unterhaltsbedarf. Seit 1962 regelt die D\u00fcsseldorfer Tabelle die H\u00f6he von Unterhaltszahlungen mit dem Ziel, die Rechtsprechung der Familiengerichte unter anderem bez\u00fcglich Kindesunterhalt zu standardisieren. <b>An der D\u00fcsseldorfer Tabelle orientieren sich die Familiengerichte bei der Festsetzung des Unterhalts, sie hat aber keine Gesetzeskraft.<\/b><\/p>\n<p>Der Kindesunterhalt ist aber nur ein Bereich der D\u00fcsseldorfer Tabelle, die insgesamt aus vier Teilen besteht: dem bereits ange\u00adsprochenen Kindesunterhalt, dem Ehegatten\u00adunter\u00adhalt, der Mangelfallberechnung und dem Verwandtenunterhalt. Das Oberlandesgericht (OLG) D\u00fcsseldorf aktualisiert die Unterhaltstabelle in Zusammenarbeit mit dem Deutschen Familiengerichtstag regelm\u00e4\u00dfig.<\/p>\n<p>In diesem Ratgeberartikel liegt der Schwerpunkt auf dem Kindesunterhalt. Sie erfahren, wie hoch der aktuelle Kindesunterhalt 2025 ist, welche Faktoren die H\u00f6he des Unterhalts beeinflussen, was in der D\u00fcsseldorfer Tabelle 2025 steht und was Sie als Eltern von Scheidungskindern tun m\u00fcssen.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow \" >\n    <div class=\"highlightbox-container\">\n                    <div class=\"highlightbox box\">\n                                    <h3                        class=\"headline headline--h3 headline--has-icon\"\n                                                    style=\"--headline-icon: url('https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2023\/10\/icon-question-dark.svg');\"\n                                            >\n                        Was bedeutet &#8222;Unterhalt zahlen&#8220;?                    <\/h3>\n                                <div class=\"box__content\">\n                                            <div class=\"flow-content\">\n                            <p>Aus rechtlicher Sicht bezeichnet der Begriff &#8222;Unterhalt&#8220; die Verpflichtung eines Einzelnen, die Existenz eines anderen Menschen zu sichern. Das deutsche Unterhaltsrecht ist im vierten Buch des B\u00fcrgerlichen Gesetzbuches (BGB) geregelt.<\/p>\n<p>Wichtig ist in diesem Zusammenhang, dass es keinen einheitlichen Unterhaltsanspruch gibt, einer Unterhaltszahlung gehen verschiedene Anspruchsgrundlagen mit unterschiedlichen Bedingungen voraus. Die D\u00fcsseldorfer Tabelle hilft dabei, diese Anspr\u00fcche und Bedingungen zu vereinfachen und zu vereinheitlichen.<\/p>\n                        <\/div>\n                                                        <\/div>\n            <\/div>\n            <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow js-is-toc\" id=\"Ab-2025-bekommen-Scheidungskinder-mehr-Geld\" >\n                <h2            class=\"headline headline--h2\"\n                    >\n            Ab 2025 bekommen Scheidungskinder mehr Geld        <\/h2>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>In der D\u00fcsseldorfer Tabelle 2025 wurden \u00c4nderungen bez\u00fcglich Kindesunterhalt zu Gunsten des Nachwuchses vorgenommen. In der Einkommensklasse bis 1900 Euro steigt der Mindestunterhalt f\u00fcr Kinder der Altersstufe bis f\u00fcnf Jahre demnach ab dem 1. Januar 2025 im Vergleich zum Vorjahr um 2 auf 482 Euro. F\u00fcr Kinder von sechs bis elf gibt es dann 554 Euro und damit 3 Euro mehr. F\u00fcr Kinder von 12 bis 17 Jahren sind es insgesamt 649 Euro \u2013 4 Euro mehr. Auch f\u00fcr vollj\u00e4hrige Kinder sowie in den weiteren Einkommensgruppen steigen die S\u00e4tze.<\/p>\n<p><b>Auf den Bedarf des Kindes wird weiterhin das Kindergeld angerechnet.<\/b> Das Kindergeld betr\u00e4gt seit dem 1. Januar 2025 einheitlich 255 Euro im Monat. Die H\u00e4lfte des Kindergelds ist zu verrechnen mit dem Kindesunterhalt.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"box box--type2 box--contrast03 newsletter newsletter--simple\">\n                    <h2                class=\"headline headline--h2 headline--has-icon newsletter__headline\"\n                style=\"--headline-icon: url('https:\/\/www.finanzen.net\/ratgeber\/wp-content\/themes\/fnet-ratgeber\/images\/icon-check-white.svg');\"\n            >\n                Wollen Sie zu aktuellen Empfehlungen rund um das Thema Recht auf dem Laufenden bleiben?            <\/h2>\n                <div class=\"box__content box__content--indent\">\n                            <div class=\"flow-content newsletter__text\">\n                    <p>Unser Tipp: Abonnieren Sie jetzt unseren kostenlosen Newsletter!<\/p>\n                <\/div>\n                        <div class=\"fnet-nl-ic__form-area js-fnet-proxy-form-container\">\n              <form class=\"form js-fnet-proxy-form\" name=\"anmelden\" action=\"\" method=\"post\" novalidate>\n                <input type=\"hidden\" class=\"js-fnet-recaptcha-token\" name=\"recaptcha-token\" value=\"\">\n                <input type=\"hidden\" name=\"type\" value=\"Ratgeber\">\n                <input type=\"hidden\" name=\"nl_refurl\" value=\"\">\n                <input type=\"hidden\" name=\"nl_refwidget\" value=\"nl-widget-article-page\">\n                <input type=\"hidden\" name=\"nl_refad\" value=\"\">\n                <input type=\"hidden\" name=\"brandedSignup\" value=\"true\">\n\n                <div class=\"form__fieldset form__fieldset--01\">\n                  <input\n                    class=\"fnet-nl-ic__input\"\n                    id=\"fnet-nl-ic-email\"\n                    type=\"email\"\n                    name=\"email\"\n                    placeholder=\"deine@email.de\"\n                    autocomplete=\"email\"\n                    required\n                  >\n\n                  <p class=\"fnet-nl-ic__error js-fnet-error\"><\/p>\n                  <div class=\"fnet-nl-ic__feedback hidden js-fnet-feedback\" aria-live=\"polite\"><\/div>\n\n                  <div class=\"recaptcha-container\">\n                    <input\n                      class=\"g-recaptcha fnet-nl-ic__btn js-fnet-proxy-submit\"\n                      id=\"fnet-nl-ic-btn\"\n                      data-sitekey=\"6LcBYcoUAAAAAMdyQNuFCMhFBfQUp1jGpohFSA4l\"\n                      data-action=\"newslettersignup\"\n                      name=\"abschicken\"\n                      type=\"button\"\n                      value=\"Jetzt anmelden \u2192\"\n                    >\n                  <\/div>\n                <\/div>\n\n                <small class=\"fnet-nl-ic__legal\">\n                  Informationen zur Verarbeitung deiner personenbezogenen Daten, insbesondere zu Verantwortlichem,\n                  Versanddienstleister, Speicherdauer sowie deinen Rechten, findest du in unserer\n                  <a href=\"https:\/\/www.finanzen.net\/datenschutz\" target=\"_blank\" rel=\"noopener noreferrer\">Datenschutzerkl\u00e4rung<\/a>.\n                <\/small>\n              <\/form>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow js-is-toc\" id=\"Wer-muss-Unterhalt-zahlen\" >\n                <h2            class=\"headline headline--h2\"\n                    >\n            Wer muss Unterhalt zahlen?        <\/h2>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Nur der Elternteil, bei dem sich das minderj\u00e4hrige und gemeinsame Kind selten oder zumindest nicht st\u00e4ndig aufh\u00e4lt, ist laut \u00a7 1612a BGB zum sogenannten Barunterhalt verpflichtet. Sind die gemeinsamen Kinder vollj\u00e4hrig und befinden sich in Ausbildung und\/oder Studium, sind sowohl Mutter als auch Vater zum Unterhalt verpflichtet. Sie zahlen dann Kindesunterhalt entsprechend ihrer finanziellen Leistungsf\u00e4higkeit.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow js-is-toc\" id=\"Wie-viel-Unterhalt-muss-ich-pro-Kind-zahlen\" >\n                <h2            class=\"headline headline--h2\"\n                    >\n            Wie viel Unterhalt muss ich pro Kind zahlen?        <\/h2>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Der Mindestunterhalt f\u00fcr minderj\u00e4hrige Trennungskinder richtet sich nach dem Existenzminimum des Kindes und der sogenannten Mindestunterhaltsverordnung (mehr dazu k\u00f6nnen Sie in <a title=\"B\u00fcrgerliches Gesetzbuch (BGB): \u00a7 1612a Mindestunterhalt minderj\u00e4hriger Kinder; Verordnungserm\u00e4chtigung\" href=\"https:\/\/www.gesetze-im-internet.de\/bgb\/__1612a.html\" target=\"_blank\" rel=\"noopener\">\u00a7 1612a BGB<\/a> nachlesen). Ab 1. Januar 2025 gelten die Mindestunterhaltss\u00e4tze, die bereits weiter oben genannt wurden und in der folgenden Tabelle \u00fcbersichtlich dargestellt werden.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow js-is-toc\" id=\"Dsseldorfer-Tabelle-2025-Kindesunterhalt\" >\n                <h2            class=\"headline headline--h2\"\n                    >\n            D\u00fcsseldorfer Tabelle 2025 Kindesunterhalt        <\/h2>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p><small>Die Tabelle hat keine Gesetzeskraft, sondern stellt eine Richtlinie dar. Sie weist den monatlichen Unterhaltsbedarf aus, bezogen auf zwei Unterhaltsberechtigte, ohne R\u00fccksicht auf den Rang. Altersgruppen in Jahren, Betr\u00e4ge in Euro, Stand: 01. Januar 2025<\/small><\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n<div class=\"container container--narrow\" id=\"duesseldorfer-tabelle-kindesunterhalt\" >\n            <h3 class=\"headline headline--h3\">\n            D\u00dcSSELDORFER TABELLE 2025 KINDESUNTERHALT        <\/h3>\n                            <div class=\"table-container\">\n        \n                <table class=\"table\">\n                                                                <thead>\n                            <tr>\n                                                                    <th>\n                                        <b>Netto\u00adeinkommen<\/b>                                    <\/th>\n                                                                    <th>\n                                        <b>0-5\nJahre<\/b>                                    <\/th>\n                                                                    <th>\n                                        <b>6-11\nJahre<\/b>                                    <\/th>\n                                                                    <th>\n                                        <b>12-17\nJahre<\/b>                                    <\/th>\n                                                                    <th>\n                                        <b>ab 18\nJahre<\/b>                                    <\/th>\n                                                                    <th>\n                                        <b>Prozent\u00adsatz<\/b>                                    <\/th>\n                                                                    <th>\n                                        <b>Bedarfs\u00adkontroll\u00adbetrag<\/b>                                    <\/th>\n                                                            <\/tr>\n                        <\/thead>\n                                                                <tbody>\n                                                            <tr>\n                                                                            <td>\n                                            bis 2.100                                        <\/td>\n                                                                            <td>\n                                            482                                        <\/td>\n                                                                            <td>\n                                            554                                        <\/td>\n                                                                            <td>\n                                            649                                        <\/td>\n                                                                            <td>\n                                            693                                        <\/td>\n                                                                            <td>\n                                            100                                        <\/td>\n                                                                            <td>\n                                            1.200 \/ 1.450                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            2.101 &#8211; 2.500                                        <\/td>\n                                                                            <td>\n                                            507                                        <\/td>\n                                                                            <td>\n                                            582                                        <\/td>\n                                                                            <td>\n                                            682                                         <\/td>\n                                                                            <td>\n                                            728                                        <\/td>\n                                                                            <td>\n                                            105                                        <\/td>\n                                                                            <td>\n                                            1.750                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            2.501 &#8211; 2.900                                         <\/td>\n                                                                            <td>\n                                            531                                        <\/td>\n                                                                            <td>\n                                            610                                        <\/td>\n                                                                            <td>\n                                            714                                         <\/td>\n                                                                            <td>\n                                            763                                        <\/td>\n                                                                            <td>\n                                            \t110                                        <\/td>\n                                                                            <td>\n                                            1.850                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            2.901 &#8211; 3.300                                        <\/td>\n                                                                            <td>\n                                            555                                        <\/td>\n                                                                            <td>\n                                            638                                        <\/td>\n                                                                            <td>\n                                            747                                        <\/td>\n                                                                            <td>\n                                            797                                        <\/td>\n                                                                            <td>\n                                            115                                        <\/td>\n                                                                            <td>\n                                            1.950                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            3.301 &#8211; 3.700                                        <\/td>\n                                                                            <td>\n                                            579                                        <\/td>\n                                                                            <td>\n                                            665                                        <\/td>\n                                                                            <td>\n                                            779                                        <\/td>\n                                                                            <td>\n                                            832                                        <\/td>\n                                                                            <td>\n                                            120                                        <\/td>\n                                                                            <td>\n                                            2.050                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            3.701 &#8211; 4.100                                        <\/td>\n                                                                            <td>\n                                            617                                        <\/td>\n                                                                            <td>\n                                            710                                        <\/td>\n                                                                            <td>\n                                            831                                        <\/td>\n                                                                            <td>\n                                            888                                        <\/td>\n                                                                            <td>\n                                            128                                        <\/td>\n                                                                            <td>\n                                            2.150                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            4.101 &#8211; 4.500                                         <\/td>\n                                                                            <td>\n                                            656                                         <\/td>\n                                                                            <td>\n                                            754                                         <\/td>\n                                                                            <td>\n                                            883                                        <\/td>\n                                                                            <td>\n                                            943                                         <\/td>\n                                                                            <td>\n                                            \t136                                        <\/td>\n                                                                            <td>\n                                            2.250                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            4.501 &#8211; 4.900                                        <\/td>\n                                                                            <td>\n                                            695                                         <\/td>\n                                                                            <td>\n                                            798                                         <\/td>\n                                                                            <td>\n                                            935                                        <\/td>\n                                                                            <td>\n                                            998                                        <\/td>\n                                                                            <td>\n                                            144                                        <\/td>\n                                                                            <td>\n                                            2.350                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            4.901 &#8211; 5.300                                        <\/td>\n                                                                            <td>\n                                            733                                         <\/td>\n                                                                            <td>\n                                            843                                         <\/td>\n                                                                            <td>\n                                            987                                        <\/td>\n                                                                            <td>\n                                            1.054                                         <\/td>\n                                                                            <td>\n                                            152                                        <\/td>\n                                                                            <td>\n                                            2.450                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            5.301 &#8211; 5.700                                        <\/td>\n                                                                            <td>\n                                            772                                         <\/td>\n                                                                            <td>\n                                            887                                        <\/td>\n                                                                            <td>\n                                            1.039                                        <\/td>\n                                                                            <td>\n                                            1.109                                         <\/td>\n                                                                            <td>\n                                            160                                        <\/td>\n                                                                            <td>\n                                            2.550                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            . 5.701 &#8211; 6.400                                        <\/td>\n                                                                            <td>\n                                            810                                        <\/td>\n                                                                            <td>\n                                            931                                        <\/td>\n                                                                            <td>\n                                            1.091                                         <\/td>\n                                                                            <td>\n                                            1.165                                        <\/td>\n                                                                            <td>\n                                            168                                        <\/td>\n                                                                            <td>\n                                            2.850                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            6.401 &#8211; 7.200                                        <\/td>\n                                                                            <td>\n                                            849                                         <\/td>\n                                                                            <td>\n                                            976                                        <\/td>\n                                                                            <td>\n                                            1.143                                        <\/td>\n                                                                            <td>\n                                            1.220                                        <\/td>\n                                                                            <td>\n                                            176                                        <\/td>\n                                                                            <td>\n                                            3.250                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            7.201 &#8211; 8.200                                         <\/td>\n                                                                            <td>\n                                            887                                        <\/td>\n                                                                            <td>\n                                            1.020                                        <\/td>\n                                                                            <td>\n                                            1.195                                        <\/td>\n                                                                            <td>\n                                            1.276                                        <\/td>\n                                                                            <td>\n                                            184                                        <\/td>\n                                                                            <td>\n                                            3.750                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            8.201 &#8211; 9.700                                        <\/td>\n                                                                            <td>\n                                            926                                        <\/td>\n                                                                            <td>\n                                            1.064                                        <\/td>\n                                                                            <td>\n                                            1.247                                        <\/td>\n                                                                            <td>\n                                            1.331                                         <\/td>\n                                                                            <td>\n                                            \t192                                        <\/td>\n                                                                            <td>\n                                            4.350                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            9.701 &#8211; 11.200                                         <\/td>\n                                                                            <td>\n                                            964                                         <\/td>\n                                                                            <td>\n                                            1.108                                        <\/td>\n                                                                            <td>\n                                            1.298                                        <\/td>\n                                                                            <td>\n                                             1.386\t                                        <\/td>\n                                                                            <td>\n                                            200                                        <\/td>\n                                                                            <td>\n                                            5.050                                        <\/td>\n                                                                    <\/tr>\n                                                    <\/tbody>\n                                    <\/table>\n                    <\/div>\n            <\/div>\n\n\n\n<div class=\"container container--narrow js-is-toc\" id=\"Dsseldorfer-Tabelle-mit-Zahlbetrgen\" >\n                <h2            class=\"headline headline--h2\"\n                    >\n            D\u00fcsseldorfer Tabelle mit Zahlbetr\u00e4gen        <\/h2>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p><strong>Wichtig:<\/strong> Der Mindestunterhalt ist nicht gleich der tats\u00e4chliche Zahlbetrag. Denn in der obigen D\u00fcsseldorfer Tabelle ist das Kindergeld noch nicht ber\u00fccksichtigt. Dieses k\u00f6nnen Sie als Unterhaltspflichtige jedoch von dem Unterhalt abziehen. Die Folge: Steigt das Kindergeld, sinken Ihre tats\u00e4chlichen Zahlbetr\u00e4ge.<\/p>\n<p>Die folgende Tabelle enth\u00e4lt die sich nach Abzug des jeweiligen Kindergeldanteils (h\u00e4lftiges Kindergeld bei Minderj\u00e4hrigen, volles Kindergeld bei Vollj\u00e4hrigen) ergebenden Zahlbetr\u00e4ge. In 2025 betr\u00e4gt das Kindergeld einheitlich je Kind 255 Euro.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n<div class=\"container container--narrow\" id=\"duesseldorfer-tabelle-kindesunterhalt\" >\n            <h3 class=\"headline headline--h3\">\n            D\u00fcsseldorfer Tabelle 2025 Unterhalt mit Zahlbeitr\u00e4gen        <\/h3>\n                            <div class=\"table-container\">\n        \n                <table class=\"table\">\n                                                                <thead>\n                            <tr>\n                                                                    <th>\n                                        <b>Netto\u00adeinkommen<\/b>                                    <\/th>\n                                                                    <th>\n                                        <b>0-5\nJahre<\/b>                                    <\/th>\n                                                                    <th>\n                                        <b>6-11\nJahre<\/b>                                    <\/th>\n                                                                    <th>\n                                        <b>12-17\nJahre<\/b>                                    <\/th>\n                                                                    <th>\n                                        <b>ab 18\nJahre<\/b>                                    <\/th>\n                                                                    <th>\n                                        <b>Prozent\u00adsatz<\/b>                                    <\/th>\n                                                            <\/tr>\n                        <\/thead>\n                                                                <tbody>\n                                                            <tr>\n                                                                            <td>\n                                            bis 2.100                                        <\/td>\n                                                                            <td>\n                                            354,50                                         <\/td>\n                                                                            <td>\n                                            426,50                                        <\/td>\n                                                                            <td>\n                                            521,50                                        <\/td>\n                                                                            <td>\n                                            438                                        <\/td>\n                                                                            <td>\n                                            100                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            2.101- 2.500                                        <\/td>\n                                                                            <td>\n                                            379,50                                         <\/td>\n                                                                            <td>\n                                            454,50                                        <\/td>\n                                                                            <td>\n                                            554,50                                        <\/td>\n                                                                            <td>\n                                            473                                        <\/td>\n                                                                            <td>\n                                            105                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            2.501- 2.900                                        <\/td>\n                                                                            <td>\n                                            403,50                                         <\/td>\n                                                                            <td>\n                                            482,50                                        <\/td>\n                                                                            <td>\n                                            586,50                                        <\/td>\n                                                                            <td>\n                                            508                                         <\/td>\n                                                                            <td>\n                                            \t110                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            2.901- 3.300                                        <\/td>\n                                                                            <td>\n                                            427,50                                         <\/td>\n                                                                            <td>\n                                            510,50                                        <\/td>\n                                                                            <td>\n                                            619,50                                        <\/td>\n                                                                            <td>\n                                            542                                        <\/td>\n                                                                            <td>\n                                            115                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            3.301- 3.700                                        <\/td>\n                                                                            <td>\n                                            451,50                                         <\/td>\n                                                                            <td>\n                                            537,50                                        <\/td>\n                                                                            <td>\n                                            651,50                                        <\/td>\n                                                                            <td>\n                                            577                                        <\/td>\n                                                                            <td>\n                                            120                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            3.701- 4.100                                        <\/td>\n                                                                            <td>\n                                            489,50                                        <\/td>\n                                                                            <td>\n                                            582,50                                        <\/td>\n                                                                            <td>\n                                            705,50                                        <\/td>\n                                                                            <td>\n                                            633                                         <\/td>\n                                                                            <td>\n                                            128                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            4.101- 4.500                                         <\/td>\n                                                                            <td>\n                                            528,50                                         <\/td>\n                                                                            <td>\n                                            626,50                                        <\/td>\n                                                                            <td>\n                                            755,50                                         <\/td>\n                                                                            <td>\n                                            688                                         <\/td>\n                                                                            <td>\n                                            \t136                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            4.501- 4.900                                        <\/td>\n                                                                            <td>\n                                            567,50                                        <\/td>\n                                                                            <td>\n                                            670,50                                        <\/td>\n                                                                            <td>\n                                            807,50                                         <\/td>\n                                                                            <td>\n                                            743                                        <\/td>\n                                                                            <td>\n                                            144                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            4.901- 5.300                                        <\/td>\n                                                                            <td>\n                                            605,50                                         <\/td>\n                                                                            <td>\n                                            715,50                                        <\/td>\n                                                                            <td>\n                                            859,50                                        <\/td>\n                                                                            <td>\n                                            799                                        <\/td>\n                                                                            <td>\n                                            152                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            5.301- 5.700                                        <\/td>\n                                                                            <td>\n                                            644,50                                        <\/td>\n                                                                            <td>\n                                            759,50                                         <\/td>\n                                                                            <td>\n                                            911,50                                        <\/td>\n                                                                            <td>\n                                            854                                        <\/td>\n                                                                            <td>\n                                            160                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            5.701- 6.400                                        <\/td>\n                                                                            <td>\n                                            682,50                                         <\/td>\n                                                                            <td>\n                                            803,50                                        <\/td>\n                                                                            <td>\n                                            963,50                                         <\/td>\n                                                                            <td>\n                                            910                                         <\/td>\n                                                                            <td>\n                                            168                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            6.401- 7.200                                         <\/td>\n                                                                            <td>\n                                            721,50                                        <\/td>\n                                                                            <td>\n                                            848,50                                         <\/td>\n                                                                            <td>\n                                            1.015,50                                         <\/td>\n                                                                            <td>\n                                            965                                         <\/td>\n                                                                            <td>\n                                            176                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            7.201- 8.200                                        <\/td>\n                                                                            <td>\n                                            759,50                                        <\/td>\n                                                                            <td>\n                                            892,50                                        <\/td>\n                                                                            <td>\n                                            1.068,50                                        <\/td>\n                                                                            <td>\n                                            1.021                                        <\/td>\n                                                                            <td>\n                                            184                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            8.201- 9.700                                         <\/td>\n                                                                            <td>\n                                            798,50                                         <\/td>\n                                                                            <td>\n                                            936,50                                        <\/td>\n                                                                            <td>\n                                            1.119,50                                        <\/td>\n                                                                            <td>\n                                            1.076                                        <\/td>\n                                                                            <td>\n                                            \t192                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            9.701- 11.200                                         <\/td>\n                                                                            <td>\n                                            836,50                                         <\/td>\n                                                                            <td>\n                                            980,50                                         <\/td>\n                                                                            <td>\n                                            1.170,50                                         <\/td>\n                                                                            <td>\n                                            1.131                                         <\/td>\n                                                                            <td>\n                                            200                                        <\/td>\n                                                                    <\/tr>\n                                                    <\/tbody>\n                                    <\/table>\n                    <\/div>\n            <\/div>\n\n\n\n<div class=\"container container--narrow js-is-toc\" id=\"Der-Kindesunterhalt-im-Einzelfall--ein-Beispiel\" >\n                <h2            class=\"headline headline--h2\"\n                    >\n            Der Kindesunterhalt im Einzelfall &#8211; ein Beispiel        <\/h2>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Um herauszufinden, welchen Betrag ein Barunterhaltspflichtiger monatlich zahlen muss respektive welcher Betrag Scheidungskindern jeden Monat von ihren geschiedenen Eltern zusteht, sind einige Daten wichtig: Nettoeinkommen des Barunterhaltspflichtigen, Alter des Kindes und verschiedene Faktoren, die den Kindesunterhalt beeinflussen wie der Eigenbedarf oder Schulden.<\/p>\n<p><b>Damit das Lesen der Tabelle leichter f\u00e4llt, hier ein kleines Beispiel:<\/b> Ihr unterhaltsrelevantes Einkommen bel\u00e4uft sich auf 3.000 Euro. Sie werden damit entsprechend in der 4. Einkommensstufe zwischen 2.901 Euro und 3.300 Euro eingestuft. Ihr Kind ist 13 Jahre alt, was der 3. Altersstufe entspricht. In diesem beispielhaften Fall weist die D\u00fcsseldorfer Tabelle einen Unterhaltsanspruch in H\u00f6he von 619,50 Euro im Monat aus.<\/p>\n<p><b>In der D\u00fcsseldorfer Tabelle wird der monatliche Unterhaltsanspruch von zwei Unterhaltsberechtigten ausgewiesen.<\/b>\u00a0Haben Sie nur ein Kind oder mehr als zwei Kinder, dann k\u00f6nnen Ab- oder Zuschl\u00e4ge angemessen sein \u2013 es erfolgt dann m\u00f6glicherweise die Einstufung in eine niedrigere oder h\u00f6here Nettoeinkommensgruppe. Welche Faktoren den Unterhaltsanspruch noch beeinflussen, zeigen wir im Folgenden auf.<\/p>\n<p>Weitere Informationen rund um den Unterhalt k\u00f6nnen Sie \u00fcbrigens auch auf der\u00a0<a class=\"broken_link\" title=\"Bundesministerium der Justiz und f\u00fcr Verbraucherschutz\" href=\"https:\/\/www.bmjv.de\/DE\/Themen\/FamilieUndPartnerschaft\/Unterhaltsrecht\/Unterhaltsrecht_node.html\" target=\"_blank\" rel=\"noopener\">Internetseite des Bundesministeriums der Justiz und f\u00fcr Verbraucherschutz<\/a>\u00a0nachlesen. Hier finden Sie au\u00dferdem alle notwendigen Antragsformulare.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n<div class=\"container container--narrow \" >\n    <div class=\"link-list box\">\n                    <h2 class=\"headline headline--h3\">\n                Das k\u00f6nnte Sie auch interessieren:            <\/h2>\n                            <ul class=\"link-list__list\">\n                                    <li class=\"link-list__item\">\n                        <a class=\"link link--arrow-right\" href=\"https:\/\/www.finanzen.net\/ratgeber\/kurzarbeit\/\" target=\"_blank\">\n                            Kurzarbeit                        <\/a>\n                    <\/li>\n                                    <li class=\"link-list__item\">\n                        <a class=\"link link--arrow-right\" href=\"https:\/\/www.finanzen.net\/ratgeber\/mutterschutzgesetz\/\" target=\"_blank\">\n                            Mutterschutzgesetz                        <\/a>\n                    <\/li>\n                                    <li class=\"link-list__item\">\n                        <a class=\"link link--arrow-right\" href=\"https:\/\/www.finanzen.net\/ratgeber\/kindergeld-kinderzuschlag\/\" target=\"_blank\">\n                            Kindergeld                        <\/a>\n                    <\/li>\n                                    <li class=\"link-list__item\">\n                        <a class=\"link link--arrow-right\" href=\"https:\/\/www.finanzen.net\/ratgeber\/krankengeld\/\" target=\"_blank\">\n                            Krankengeld                        <\/a>\n                    <\/li>\n                            <\/ul>\n            <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow js-is-toc\" id=\"Wie-wird-die-Dsseldorfer-Tabelle-berechnet\" >\n                <h2            class=\"headline headline--h2\"\n                    >\n            Wie wird die D\u00fcsseldorfer Tabelle berechnet?        <\/h2>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Das unterhaltsrelevante Nettoeinkommen zu ermitteln, ist in der Praxis die gr\u00f6\u00dfte Schwierigkeit. Mit dem Nettoeinkommen auf der Gehalts- oder Lohnabrechnung hat dies in den seltensten F\u00e4llen zu tun&nbsp;&#8211; dazu und zu den Begrifflichkeiten der Tabelle im Folgenden mehr.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow\" >\n                <h4            class=\"headline headline--h4\"\n                    >\n            Unterhaltsbedarf und Zahlbetrag        <\/h4>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Die obige Tabelle hat keine Gesetzeskraft, sie stellt vielmehr eine Richtlinie dar. In der Tabelle wird der monatliche Unterhalts<b>bedarf<\/b> bezogen auf zwei Unterhaltsberechtigte ausgewiesen. Der ausgewiesene Bedarf ist nicht identisch mit dem <b>Zahlbetrag<\/b>. Der Zahlbetrag \u00e4ndert sich beispielsweise bei einer gr\u00f6\u00dferen oder geringeren Anzahl Unterhaltsberechtigter. Dann k\u00f6nnen Ab- oder Zuschl\u00e4ge angemessen sein, die eine Einstufung in einer niedrigeren oder h\u00f6heren Gruppe nach sich zieht. Um den notwendigen Mindestbedarf zu decken, kann gebenenfalls eine Herabstufung bis in die unterste Tabellengruppe notwendig sein.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow\" >\n                <h4            class=\"headline headline--h4\"\n                    >\n            Notwendiger und angemessener Eigenbedarf        <\/h4>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Sollte das verf\u00fcgbare Einkommen auch dann nicht ausreichen, m\u00fcssen die Interessen der Kinder h\u00f6her bewertet werden als die des\/der Unterhaltspflichtigen. Das hei\u00dft: <b>Der notwendige Eigenbedarf (Selbstbehalt) betr\u00e4gt beim nicht erwerbst\u00e4tigen Unterhaltspflichtigen 1.200 Euro pro Monat, beim erwerbst\u00e4tigen Unterhaltspflichtigen jeden Monat 1.450 Euro.<\/b> Hierin enthalten sind bis zu 520 Euro f\u00fcr Unterkunft einschlie\u00dflich umlagef\u00e4higer Nebenkosten und Heizung (Warmmiete). \u00dcberschreitet die Warmmiete den ausgewiesenen Betrag und in nicht unangemessener Weise, dann soll der Selbstbehalt erh\u00f6ht werden. <b>Der angemessene Eigenbedarf betr\u00e4gt normalerweise mindestens 1.750 Euro monatlich<\/b> &#8211; insbesondere gegen\u00fcber anderen vollj\u00e4hrigen Kindern. In diesem Betrag ist eine Warmmiete bis zu 650 Euro inklusive.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow\" >\n                <h4            class=\"headline headline--h4\"\n                    >\n            Nettoeinkommen des\/der Barunterhaltspflichtigen        <\/h4>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Am Nettoeinkommen des oder der Barunterhaltspflichtigen errechnet sich der Kindesunterhalt. Von diesem Einkommen abzuziehen sind berufsbedingte Aufwendungen, die sich von den privaten Lebenshaltungskosten eindeutig abgrenzen lassen. Dieser Betrag kann auch pauschal auf 5 Prozent des Nettoeinkommens gesch\u00e4tzt werden, dabei k\u00f6nnen mindestens 50 Euro (bei geringf\u00fcgiger Teilzeitarbeit auch weniger) und h\u00f6chstens 150 Euro pro Monat angesetzt werden. Wenn die berufsbedingten Aufwendungen die Pauschale \u00fcbersteigen, dann m\u00fcssen diese insgesamt belegt werden.<\/p>\n<p><b>Schulden, sofern diese \u201eber\u00fccksichtigungsf\u00e4hig\u201c sind, sind in der Regel vom Einkommen abzuziehen.<\/b>\u00a0Ber\u00fccksichtigungsf\u00e4hig sind unter anderem Schulden, die bereits w\u00e4hrend des Zusammenlebens der Eltern gemacht wurden. Diese sind abziehbar, solange wenigstens der Mindestunterhalt (niedrigster Satz der D\u00fcsseldorfer Tabelle) gew\u00e4hrleistet ist.<\/p>\n<p>Schulden, die vor Geburt des Kindes gemacht wurden, sind ebenfalls ber\u00fccksichtigungsf\u00e4hig. Das k\u00f6nnen beispielsweise BAf\u00f6G-Schulden eines Elternteils oder Schulden zur Einrichtung der Wohnung sein. Bei Schulden, die sp\u00e4ter angeh\u00e4uft wurden, ist der Grund der Verbindlichkeit entscheidend. Schulden, die durch den Kauf eines (unn\u00f6tig) teuren Autos oder f\u00fcr eine Weltreise gemacht wurden, sind nicht abziehbar.<\/p>\n<p><strong><span class=\"lightbulb-text\">Tipp:<\/span>\u00a0<\/strong>Einen \u00dcberblick \u00fcber die Leitlinien zum Unterhalt der D\u00fcsseldorfer Tabelle erhalten Sie auf der\u00a0<a title=\"OLG D\u00fcsseldorf: Leitlinien zum Unterhalt \" href=\"https:\/\/www.olg-duesseldorf.nrw.de\/infos\/Duesseldorfer_Tabelle\/Tabelle-2023\/Duesseldorfer-Tabelle-2023.pdf\" target=\"_blank\" rel=\"noopener\">Internetseite des OLG D\u00fcsseldorf<\/a>. Dort finden Sie Informationen zum unterhaltsrechlichen Einkommen, zum Kindesunterhalt, zum Ehegattenunterhalt sowie zum sogenannten Mangelfall.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow\" >\n                <h4            class=\"headline headline--h4\"\n                    >\n            Prozentsatz        <\/h4>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Die erste Einkommensgruppe (bis 2.100 Euro) ist Ausgangspunkt f\u00fcr die weiteren Berechnungen in der D\u00fcsseldorfer Tabelle. In der ersten Zeile wird der Mindestunterhalt ausgewiesen (482 Euro), der Prozentsatz betr\u00e4gt entsprechend 100 Prozent.<\/p>\n<p>Alle weiteren (h\u00f6heren) Prozents\u00e4tze dr\u00fccken die Steigerung des Unterhalts der jeweiligen Einkommensgruppe gegen\u00fcber dem Mindestunterhalt in der ersten Einkommensgruppe aus. Wird nun der Mindestunterhalt einer Altersstufe, zum Beispiel 649 Euro f\u00fcr die Altersstufe 3 (12 bis 17 Jahre), mit dem Prozentsatz einer bestimmten Einkommensstufe, zum Beispiel 110 Prozent bei Einkommensstufe 3 (2.501 bis 2.900 Euro), multipliziert, dann ergibt sich die H\u00f6he des Unterhaltsanspruchs. Diesen k\u00f6nnen Sie als entsprechenden Eurobetrag in der Tabelle ablesen, in diesem Beispiel sind dies 714 Euro.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow\" >\n                <h4            class=\"headline headline--h4\"\n                    >\n            Bedarfskontrollbetrag        <\/h4>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Der Bedarfskontrollbetrag ist nicht identisch mit dem Eigenbedarf.\u00a0<b>Dieser Wert dient der Vorsorge einer Ungleichbehandlung<\/b>\u00a0und soll eine ausgewogene Verteilung des Einkommens zwischen dem Unterhaltspflichtigen und den unterhaltsberechtigten Kindern gew\u00e4hrleisten. So soll vermieden werden, dass der Unterhaltspflichtige finanziell schlechter gestellt ist als die Unterhaltsberechtigten.<\/p>\n<p>Wird der Bedarfskontrollbetrag unter Ber\u00fccksichtigung anderer Unterhaltspflichten unterschritten, so wird der Tabellenbetrag der n\u00e4chst niedrigeren Gruppe angesetzt, deren Bedarfskontrollbetrag nicht unterschritten wird.<\/p>\n<p><strong><span class=\"lightbulb-text\">Tipp:<\/span><\/strong> Weitere Anmerkungen zur D\u00fcsseldorfer Tabelle 2025 und zur Berechnung des Kindesunterhalts finden Sie auf der <a title=\"OLG D\u00fcsseldorf: D\u00fcsseldorfer Tabelle\" href=\"https:\/\/www.olg-duesseldorf.nrw.de\/infos\/Duesseldorfer_Tabelle\/Tabelle-2022\/Duesseldorfer-Tabelle-2022.pdf\" target=\"_blank\" rel=\"noopener\">Internetseite des OLG D\u00fcsseldorf<\/a>. Dort erfahren Sie auch, welchen Kindesunterhalt Sie als Unterhaltspflichtiger leisten m\u00fcssen, wenn Sie nur ein Kind oder wenn Sie mehr als zwei Kinder haben.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow\" >\n                <h2            class=\"headline headline--h2\"\n                    >\n            D\u00fcsseldorfer Tabelle 2025 &#8211; das sollten Sie tun        <\/h2>\n        <\/div>\n\n\n\n<div class=\"container container--narrow \" >\n            <ol class=\"ordered-list ordered-list--type1\">\n                           <li class=\"ordered-list__item\">\n                    <div class=\"ordered-list__content\">\n                                                                            <div class=\"ordered-list__text\">\n                                <p>\u00dcberpr\u00fcfen Sie, wie hoch Ihr unterhaltsrelevantes Nettoeinkommen ist. Gibt es beispielsweise Schulden, die ber\u00fccksichtigungsf\u00e4hig sind?<\/p>\n                            <\/div>\n                                            <\/div>\n                <\/li>\n                            <li class=\"ordered-list__item\">\n                    <div class=\"ordered-list__content\">\n                                                                            <div class=\"ordered-list__text\">\n                                <p>Bedenken Sie, dass Sie wegen der Erh\u00f6hung des Kindesunterhalts bei gleichbleibendem Kindergeld mehr Unterhalt an Ihre Kinder zahlen m\u00fcssen.<\/p>\n                            <\/div>\n                                            <\/div>\n                <\/li>\n                            <li class=\"ordered-list__item\">\n                    <div class=\"ordered-list__content\">\n                                                                            <div class=\"ordered-list__text\">\n                                <p>Hat sich an Ihrer beruflichen Situation oder an Ihrer Einkommenssituation etwas ge\u00e4ndert, dann bedenken Sie dies beim Kindesunterhalt.<\/p>\n                            <\/div>\n                                            <\/div>\n                <\/li>\n                    <\/ol>\n    <\/div>\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"disclaimer flow-content\">\n                    <small>\n                <p style=\"font-size: 11pt;\">Disclaimer: Die in diesem Artikel enthaltenen Inhalte dienen ausschlie\u00dflich allgemeinen Informations-, Bildungs- und Marketingzwecken ohne Gew\u00e4hr auf Vollst\u00e4ndigkeit, Richtigkeit und Aktualit\u00e4t. Die Inhalte stellen keine Anlageberatung, Anlagestrategieempfehlung oder Aufforderung zum Kauf oder Verkauf von Wertpapieren oder sonstigen Finanzinstrumenten dar. Die Informationen ber\u00fccksichtigen nicht die individuellen Anlageziele und finanzielle Situation des Lesers. Jede Anlageentscheidung sollte eigenverantwortlich getroffen und sorgf\u00e4ltig gepr\u00fcft werden. Vor einer Anlageentscheidung sollte der Rat eines Anlage- und Steuerberaters eingeholt werden. Der Handel mit Wertpapieren oder sonstigen Finanzinstrumenten ist mit hohen Risiken verbunden, bis hin zum Totalverlust des eingesetzten Kapitals. Die in der Vergangenheit erzielte Performance ist kein Indikator f\u00fcr zuk\u00fcnftige Wertentwicklungen. Aussagen \u00fcber zuk\u00fcnftige wirtschaftliche Entwicklungen basieren grunds\u00e4tzlich auf Annahmen und Einsch\u00e4tzungen, die sich im Zeitablauf als nicht zutreffend erweisen k\u00f6nnen. Wir \u00fcbernehmen keine Haftung f\u00fcr Verluste, die durch die Umsetzung der in diesem Artikel genannten Informationen entstehen.<\/p>\n<p style=\"font-size: 11pt;\"><sup>1<\/sup>Hinweis zu ZERO: <a href=\"https:\/\/www.finanzen.net\/zero\/?utm_source=finnet-ratgeber&amp;utm_medium=web&amp;utm_term=fnet_017m&amp;utm_campaign=content&amp;utm_content=[current_slug]\" target=\"_blank\" rel=\"noopener\">finanzen.net zero<\/a> ist ein Angebot der <a href=\"https:\/\/www.finanzen.net\/zero\/impressum\/?utm_source=finnet-ratgeber&amp;utm_medium=web&amp;utm_term=fnet_017m&amp;utm_campaign=content&amp;utm_content=[current_slug]\" target=\"_blank\" rel=\"noopener\">finanzen.net zero GmbH<\/a>, einer Tochter der <a href=\"https:\/\/www.finanzen.net\/impressum\">finanzen.net GmbH<\/a>.<\/p>\n<p style=\"font-size: 11pt;\"><sup>*<\/sup>Hinweis zu Affiliate-Links: Unsere Ratgeber-Artikel sind objektiv und unabh\u00e4ngig erstellt, wobei mit Sternchen gekennzeichnete Links zur Finanzierung der kostenlosen Inhalte dienen. Die Verg\u00fctung aus diesen Links hat keinen Einfluss auf unsere Inhalte.<\/p>\n            <\/small>\n                    <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Wie hoch der Kindesunterhalt aktuell ist und was Sie als Eltern tun m\u00fcssen<\/p>\n","protected":false},"author":16,"featured_media":2422,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1443],"tags":[],"class_list":["post-1495","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"acf":[],"yoast_head":"<title>D\u00fcsseldorfer Tabelle 2025: So viel Unterhalt steht Scheidungskindern zu | finanzen.net<\/title>\n<meta name=\"description\" content=\"Die D\u00fcsseldorfer Tabelle 2025 zeigt, welcher Unterhalt Scheidungskindern zusteht: Die aktuelle Unterhaltstabelle und Ihre Rechte zum Kindesunterhalt!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.finanzen.net\/ratgeber\/allgemein\/duesseldorfer-tabelle-kindesunterhalt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00fcsseldorfer Tabelle 2025: So viel Unterhalt steht Scheidungskindern zu | finanzen.net\" \/>\n<meta property=\"og:description\" content=\"Die D\u00fcsseldorfer Tabelle 2025 zeigt, welcher Unterhalt Scheidungskindern zusteht: Die aktuelle Unterhaltstabelle und Ihre Rechte zum Kindesunterhalt!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.finanzen.net\/ratgeber\/allgemein\/duesseldorfer-tabelle-kindesunterhalt\/\" \/>\n<meta property=\"og:site_name\" content=\"Finanzen.net Ratgeber: Finanzwissen, das dich weiterbringt\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-29T16:17:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-11T15:07:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2018\/11\/R2.0_Duesseldorfer_Tabelle.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1152\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redaktion Ratgeber\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redaktion Ratgeber\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>","yoast_head_json":{"title":"D\u00fcsseldorfer Tabelle 2025: So viel Unterhalt steht Scheidungskindern zu | finanzen.net","description":"Die D\u00fcsseldorfer Tabelle 2025 zeigt, welcher Unterhalt Scheidungskindern zusteht: Die aktuelle Unterhaltstabelle und Ihre Rechte zum Kindesunterhalt!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.finanzen.net\/ratgeber\/allgemein\/duesseldorfer-tabelle-kindesunterhalt\/","og_locale":"de_DE","og_type":"article","og_title":"D\u00fcsseldorfer Tabelle 2025: So viel Unterhalt steht Scheidungskindern zu | finanzen.net","og_description":"Die D\u00fcsseldorfer Tabelle 2025 zeigt, welcher Unterhalt Scheidungskindern zusteht: Die aktuelle Unterhaltstabelle und Ihre Rechte zum Kindesunterhalt!","og_url":"https:\/\/www.finanzen.net\/ratgeber\/allgemein\/duesseldorfer-tabelle-kindesunterhalt\/","og_site_name":"Finanzen.net Ratgeber: Finanzwissen, das dich weiterbringt","article_published_time":"2018-11-29T16:17:44+00:00","article_modified_time":"2025-11-11T15:07:50+00:00","og_image":[{"width":1920,"height":1152,"url":"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2018\/11\/R2.0_Duesseldorfer_Tabelle.jpg","type":"image\/jpeg"}],"author":"Redaktion Ratgeber","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"Redaktion Ratgeber","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.finanzen.net\/ratgeber\/allgemein\/duesseldorfer-tabelle-kindesunterhalt\/#article","isPartOf":{"@id":"https:\/\/www.finanzen.net\/ratgeber\/allgemein\/duesseldorfer-tabelle-kindesunterhalt\/"},"author":{"name":"Redaktion Ratgeber","@id":"https:\/\/www.finanzen.net\/ratgeber\/#\/schema\/person\/7de2b54939f007854918b2e05989b109"},"headline":"D\u00fcsseldorfer Tabelle 2025","datePublished":"2018-11-29T16:17:44+00:00","dateModified":"2025-11-11T15:07:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.finanzen.net\/ratgeber\/allgemein\/duesseldorfer-tabelle-kindesunterhalt\/"},"wordCount":2193,"image":{"@id":"https:\/\/www.finanzen.net\/ratgeber\/allgemein\/duesseldorfer-tabelle-kindesunterhalt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2018\/11\/R2.0_Duesseldorfer_Tabelle.jpg","inLanguage":"de"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.finanzen.net\/ratgeber\/allgemein\/duesseldorfer-tabelle-kindesunterhalt\/","url":"https:\/\/www.finanzen.net\/ratgeber\/allgemein\/duesseldorfer-tabelle-kindesunterhalt\/","name":"D\u00fcsseldorfer Tabelle 2025: So viel Unterhalt steht Scheidungskindern zu | finanzen.net","isPartOf":{"@id":"https:\/\/www.finanzen.net\/ratgeber\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.finanzen.net\/ratgeber\/allgemein\/duesseldorfer-tabelle-kindesunterhalt\/#primaryimage"},"image":{"@id":"https:\/\/www.finanzen.net\/ratgeber\/allgemein\/duesseldorfer-tabelle-kindesunterhalt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2018\/11\/R2.0_Duesseldorfer_Tabelle.jpg","datePublished":"2018-11-29T16:17:44+00:00","dateModified":"2025-11-11T15:07:50+00:00","author":{"@id":"https:\/\/www.finanzen.net\/ratgeber\/#\/schema\/person\/7de2b54939f007854918b2e05989b109"},"description":"Die D\u00fcsseldorfer Tabelle 2025 zeigt, welcher Unterhalt Scheidungskindern zusteht: Die aktuelle Unterhaltstabelle und Ihre Rechte zum Kindesunterhalt!","breadcrumb":{"@id":"https:\/\/www.finanzen.net\/ratgeber\/allgemein\/duesseldorfer-tabelle-kindesunterhalt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.finanzen.net\/ratgeber\/allgemein\/duesseldorfer-tabelle-kindesunterhalt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.finanzen.net\/ratgeber\/allgemein\/duesseldorfer-tabelle-kindesunterhalt\/#primaryimage","url":"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2018\/11\/R2.0_Duesseldorfer_Tabelle.jpg","contentUrl":"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2018\/11\/R2.0_Duesseldorfer_Tabelle.jpg","width":1920,"height":1152},{"@type":"BreadcrumbList","@id":"https:\/\/www.finanzen.net\/ratgeber\/allgemein\/duesseldorfer-tabelle-kindesunterhalt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.finanzen.net\/ratgeber\/"},{"@type":"ListItem","position":2,"name":"Allgemein","item":"https:\/\/www.finanzen.net\/ratgeber\/.\/allgemein\/"},{"@type":"ListItem","position":3,"name":"D\u00fcsseldorfer Tabelle 2025"}]},{"@type":"WebSite","@id":"https:\/\/www.finanzen.net\/ratgeber\/#website","url":"https:\/\/www.finanzen.net\/ratgeber\/","name":"Finanzen.net Ratgeber - Die Ganze Welt der Finanzen","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.finanzen.net\/ratgeber\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.finanzen.net\/ratgeber\/#\/schema\/person\/7de2b54939f007854918b2e05989b109","name":"Redaktion Ratgeber","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/image-6-150x150.png","url":"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/image-6-150x150.png","contentUrl":"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/image-6-150x150.png","caption":"Redaktion Ratgeber"},"url":"https:\/\/www.finanzen.net\/ratgeber\/author\/team-ratgeber\/"}]}},"_links":{"self":[{"href":"https:\/\/www.finanzen.net\/ratgeber\/wp-json\/wp\/v2\/posts\/1495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.finanzen.net\/ratgeber\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.finanzen.net\/ratgeber\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.finanzen.net\/ratgeber\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.finanzen.net\/ratgeber\/wp-json\/wp\/v2\/comments?post=1495"}],"version-history":[{"count":6,"href":"https:\/\/www.finanzen.net\/ratgeber\/wp-json\/wp\/v2\/posts\/1495\/revisions"}],"predecessor-version":[{"id":26454,"href":"https:\/\/www.finanzen.net\/ratgeber\/wp-json\/wp\/v2\/posts\/1495\/revisions\/26454"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.finanzen.net\/ratgeber\/wp-json\/wp\/v2\/media\/2422"}],"wp:attachment":[{"href":"https:\/\/www.finanzen.net\/ratgeber\/wp-json\/wp\/v2\/media?parent=1495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.finanzen.net\/ratgeber\/wp-json\/wp\/v2\/categories?post=1495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.finanzen.net\/ratgeber\/wp-json\/wp\/v2\/tags?post=1495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}