{"id":1583,"date":"2020-12-02T23:39:18","date_gmt":"2020-12-02T22:39:18","guid":{"rendered":"https:\/\/www.finanzen.net\/ratgeber\/boerse\/https-www-finanzen-net-ratgeber-die-besten-stiftungsfonds-wie-koennen-sie-in-die-mischfonds-investieren-und-welche-lohnen-sich\/"},"modified":"2026-05-19T18:59:41","modified_gmt":"2026-05-19T16:59:41","slug":"stiftungsfonds-vergleich","status":"publish","type":"post","link":"https:\/\/www.finanzen.net\/ratgeber\/fonds\/produkte-vergleiche\/stiftungsfonds-vergleich\/","title":{"rendered":"Stiftungsfonds"},"content":{"rendered":"\n<div class=\"container container--narrow\">\n    <div class=\"header\">\n                    <div class=\"header__image\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"882\" src=\"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/shutterstock_2299627889-PhotoRoom.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/shutterstock_2299627889-PhotoRoom.jpg 1920w, https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/shutterstock_2299627889-PhotoRoom-300x138.jpg 300w, https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/shutterstock_2299627889-PhotoRoom-1024x470.jpg 1024w, https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/shutterstock_2299627889-PhotoRoom-768x353.jpg 768w, https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/shutterstock_2299627889-PhotoRoom-1536x706.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>                            <\/div>\n                <div class=\"header__text\">\n                            <div class=\"headline headline--preline headline--h4 header__preline\">\n                    In Stiftungsfonds investieren                <\/div>\n                                        <h1 class=\"headline headline--h1 header__headline headline--has-preline\">\n                    Stiftungsfonds-Vergleich: So investieren Anleger in die besten Stiftungsfonds                <\/h1>\n                        <div class=\"header__excerpt flow-content\">\n                                    <p>Stiftungsfonds sind Investmentfonds, die explizit f\u00fcr Stiftungen aufgelegt werden.\u00a0Wir verraten, welche Stiftungsfonds sich lohnen, wie Anleger Stiftungsfonds kaufen k\u00f6nnen und worauf sie dabei achten m\u00fcssen. In unserem Stiftungsfonds-Vergleich stellen wir die besten Stiftungsfonds f\u00fcr Sie vor. Gleich zu Beginn gibt&#8217;s die besten Empfehlungen und Tipps.<\/p>\n                            <\/div>\n            <div class=\"header__footer\">\n                <span class=\"header__meta\">\n                    <img loading=\"lazy\" decoding=\"async\" class=\"header__author-image\"\n                         src=\"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/image-6-150x150.png\"\n                         width=\"58\"\n                         height=\"58\"\n                         alt=\"\">\n                    <span class=\"header__meta-info\">\n                        <span class=\"header__author-name\">\n                            von <a href=\"https:\/\/www.finanzen.net\/ratgeber\/author\/team-ratgeber\/\" rel=\"author\" class=\"link link--no-underline\">Redaktion Ratgeber<\/a>                        <\/span>\n                        <span class=\"header__date\">\n                            <span class=\"hide-on-smartphone\">Aktualisiert am<\/span>\n                            <time datetime=\"2026-05-19 18:59\"\n                                  title=\"Aktualisiert am 19.05.2026\">\n                                19.05.26                            <\/time>\n                        <\/span>\n                    <\/span>\n                <\/span>\n\n                                    <div class=\"header__buttons\">\n                                                    <a class=\"fnet-button fnet-button--small\"\n                                                                  style=\"--button-background:#5396fc;--button-hover-background:#5396fc;\"\n                                                              href=\"https:\/\/www.finanzen.net\/ratgeber\/rechner-vergleiche\/etf-rechner\/\"\n                               target=\"\">\n                                zum Sparplanrechner                            <\/a>\n                                            <\/div>\n                            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow\">\n    <div class=\"box box--type2 box--contrast01 box--small-margin short-info\">\n        <h3 class=\"headline headline--h3 headline--has-icon short-info__headline\" style=\"--headline-icon: url('https:\/\/www.finanzen.net\/ratgeber\/wp-content\/themes\/fnet-ratgeber\/images\/icon-lightbulb-white.svg');\">\n                            Das Wichtigste in K\u00fcrze                    <\/h3>\n        <div class=\"box__content\">\n                            <div class=\"flow-content\">\n                    <ul>\n<li class=\"listing-text\">Stiftungsfonds eignen sich f\u00fcr defensive Anleger, f\u00fcr die die Sicherheit der <a href=\"https:\/\/www.finanzen.net\/ratgeber\/trading\/grundlagen-einstieg\/geldanlage\/\" data-ilm-light=\"32\" title=\"Geldanlage\">Geldanlage<\/a> besonders wichtig ist.<\/li>\n<li class=\"listing-text\"><span class=\"lightbulb-text\">Unsere Empfehlung:<\/span>\u00a0Der BKC Treuhand Portfolio, der FvS Stiftung und der DWS Stiftungsfonds geh\u00f6ren zu den besten Produkten in unserem\u00a0<a href=\"#stiftungsfonds-vergleich\">Stiftungsfonds-Vergleich<\/a>.<\/li>\n<li class=\"listing-text\"><strong><span class=\"lightbulb-text\">Tipp:<\/span><\/strong>\u00a0Inzwischen lassen sich auch Stiftungsfonds mit einem dynamischen Anlageprofil finden. F\u00fcr Anleger mit einer solchen Ausrichtung lohnt sich ein detaillierter Blick auf unseren\u00a0<a href=\"#stiftungsfonds-vergleich\">Stiftungsfonds-Vergleich<\/a>, in dem wir eine Vielzahl an Produkten genau unter die Lupe nehmen.<\/li>\n<li>\n<div class=\"listing-text\">Stiftungsfonds sind speziell f\u00fcr Stiftungen angelegte Investmentfonds. In der Regel sind Stiftungsfonds kosteng\u00fcnstige Mischfonds mit defensiver Ausrichtung.<\/div>\n<\/li>\n<li>\n<div class=\"listing-text\">Stiftungsfonds sind nicht nur f\u00fcr Stiftungen. Auch andere\u00a0<a href=\"#fonds-fuer-non-profit-organisationen\">Non-Profit-Organisationen<\/a>\u00a0halten sich an das gleiche Prinzip.<\/div>\n<\/li>\n<li>\n<div class=\"listing-text\"><strong><span class=\"important-text\">Wichtig:<\/span><\/strong> Da bei Stiftungsfonds in der Regel die Stabilit\u00e4t des Fonds im Vordergrund steht, geht das Risikomanagement vor der Renditesteigerung.<\/div>\n<\/li>\n<\/ul>\n                <\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow\">\n    <div class=\"box toc\">\n        <h3 class=\"headline headline--h3 headline--has-icon\" style=\"--headline-icon: url('https:\/\/www.finanzen.net\/ratgeber\/wp-content\/themes\/fnet-ratgeber\/images\/icon-list-blue.svg');\">\n                            Inhaltsverzeichnis                    <\/h3>\n        <div class=\"box__content\">\n            <ol class=\"toc__list js-toc-list\">\n                <!-- content generated by toc.js -->\n                            <\/ol>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow js-is-toc\" id=\"Was-sind-Stiftungsfonds\" >\n                <h2            class=\"headline headline--h2\"\n                    >\n            Was sind Stiftungsfonds?        <\/h2>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Der Begriff \u201eStiftungsfonds\u201c ist zwar nicht allgemeing\u00fcltig definiert, haben aber folgende Eigenschaften: Stiftungsfonds sind Investmentfonds, die explizit f\u00fcr Stiftungen aufgelegt werden. Fondsspezialisten bezeichnen sie auch gerne als \u201eStift\u201c.<\/p>\n<p>Der Begriff \u201eStiftungsfonds\u201c ist allerdings nicht gesch\u00fctzt. Das hat zur Folge, dass sich die Fonds nicht an standardisierte Vorgaben zum Investmentansatz oder Anlagestil halten m\u00fcssen. Trotzdem haben Stiftungen, die in solche Fonds investieren, sehr konkrete Anlagebed\u00fcrfnisse: Einerseits sollen die Investitionen hohe Ertr\u00e4ge erwirtschaften, gleichzeitig darf das investierte Kapital keinen zu hohen Risiken ausgesetzt sein. Bei Stiftungfonds handelt sich deshalb in der Regel um\u00a0<a title=\"Mischfonds kaufen \u2013 mit gemischten Fonds Risiko minimieren\" href=\"https:\/\/www.finanzen.net\/ratgeber\/wertpapiere\/mischfonds-kaufen\">Mischfonds<\/a>\u00a0mit konservativer Anlagestrategie und geringen\u00a0<a title=\"Auf einen Blick: Die wichtigsten Fondskosten\" href=\"https:\/\/www.finanzen.net\/ratgeber\/auf-einen-blick-die-wichtigsten-fondskosten\">Kosten<\/a>. Sie besitzen meistens einen Aktienanteil von bis zu 30 Prozent und sch\u00fctten j\u00e4hrlich Ertr\u00e4ge aus.<\/p>\n<p><strong><span class=\"important-text\">Hinweis:<\/span>\u00a0<\/strong>In unserem\u00a0<a title=\"Ausgabeaufschlag, Tracking Error, thesaurierend \u2013 Begriffe rund um ETFs und Fonds schnell erkl\u00e4rt\" href=\"https:\/\/www.finanzen.net\/ratgeber\/wertpapiere\/etf-lexikon\">Lexikon<\/a>\u00a0erl\u00e4utern wir alle Begriffe rund um Investmentfonds und ETFs, zum Beispiel Ausgabeaufschlag und thesaurierend.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"box box--type2 box--contrast03 newsletter newsletter--simple\">\n                    <h2                class=\"headline headline--h2 headline--has-icon newsletter__headline\"\n                style=\"--headline-icon: url('https:\/\/www.finanzen.net\/ratgeber\/wp-content\/themes\/fnet-ratgeber\/images\/icon-check-white.svg');\"\n            >\n                Wollen Sie zu aktuellen Empfehlungen rund um das Thema ETF auf dem Laufenden bleiben?            <\/h2>\n                <div class=\"box__content box__content--indent\">\n                            <div class=\"flow-content newsletter__text\">\n                    <p>Unser Tipp: Abonnieren Sie jetzt unseren kostenlosen Newsletter!<\/p>\n                <\/div>\n                        <div class=\"fnet-nl-ic__form-area js-fnet-proxy-form-container\">\n              <form class=\"form js-fnet-proxy-form\" name=\"anmelden\" action=\"\" method=\"post\" novalidate>\n                <input type=\"hidden\" class=\"js-fnet-recaptcha-token\" name=\"recaptcha-token\" value=\"\">\n                <input type=\"hidden\" name=\"type\" value=\"Ratgeber\">\n                <input type=\"hidden\" name=\"nl_refurl\" value=\"\">\n                <input type=\"hidden\" name=\"nl_refwidget\" value=\"nl-widget-article-page\">\n                <input type=\"hidden\" name=\"nl_refad\" value=\"\">\n                <input type=\"hidden\" name=\"brandedSignup\" value=\"true\">\n\n                <div class=\"form__fieldset form__fieldset--01\">\n                  <input\n                    class=\"fnet-nl-ic__input\"\n                    id=\"fnet-nl-ic-email\"\n                    type=\"email\"\n                    name=\"email\"\n                    placeholder=\"deine@email.de\"\n                    autocomplete=\"email\"\n                    required\n                  >\n\n                  <p class=\"fnet-nl-ic__error js-fnet-error\"><\/p>\n                  <div class=\"fnet-nl-ic__feedback hidden js-fnet-feedback\" aria-live=\"polite\"><\/div>\n\n                  <div class=\"recaptcha-container\">\n                    <input\n                      class=\"g-recaptcha fnet-nl-ic__btn js-fnet-proxy-submit\"\n                      id=\"fnet-nl-ic-btn\"\n                      data-sitekey=\"6LcBYcoUAAAAAMdyQNuFCMhFBfQUp1jGpohFSA4l\"\n                      data-action=\"newslettersignup\"\n                      name=\"abschicken\"\n                      type=\"button\"\n                      value=\"Jetzt anmelden \u2192\"\n                    >\n                  <\/div>\n                <\/div>\n\n                <small class=\"fnet-nl-ic__legal\">\n                  Informationen zur Verarbeitung deiner personenbezogenen Daten, insbesondere zu Verantwortlichem,\n                  Versanddienstleister, Speicherdauer sowie deinen Rechten, findest du in unserer\n                  <a href=\"https:\/\/www.finanzen.net\/datenschutz\" target=\"_blank\" rel=\"noopener noreferrer\">Datenschutzerkl\u00e4rung<\/a>.\n                <\/small>\n              <\/form>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow\" id=\"fonds-fuer-non-profit-organisationen\" >\n                <h3            class=\"headline headline--h3\"\n                    >\n            Stiftungsfonds: Nicht nur f\u00fcr Stiftungen        <\/h3>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Vereine, gGmbHs und andere Non-Profit-Organisationen halten sich bei Verm\u00f6gensanlagen in den meisten F\u00e4llen an das gleiche Prinzip: Das Geld soll rentabel und sicher angelegt werden, ohne dass dabei gro\u00dfe Kosten entstehen. In Niedrigzinsphasen achten Anleger besonders auf das Risikomanagement solcher Fonds. Sollten sie mit Anleihen kaum noch Rendite generieren, dann muss der Investmentfonds so konstruiert sein, dass er in m\u00f6glichen Krisenzeiten m\u00f6glichst stabil aufgestellt ist. Durch Aktien erlittene Verluste k\u00f6nnen dann mithilfe von Anleihen ausgeglichen werden. Es ist in diesem Fall also besser, auf den einen oder anderen Prozentpunkt in der Rendite zu verzichten, um ein funktionierendes Risikomanagement zu haben.<\/p>\n<p><strong><span class=\"lightbulb-text\">Tipp:<\/span><\/strong>\u00a0Wie Anleger\u00a0<a title=\"Fonds kaufen\" href=\"https:\/\/www.finanzen.net\/ratgeber\/wertpapiere\/fonds-kaufen\">Fonds kaufen<\/a>\u00a0k\u00f6nnen, verraten wir in unserem gleichnamigen Ratgeber. Dort finden Sie auch wichtige Tipps rund um den Fondshandel.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow\" >\n                <h3            class=\"headline headline--h3\"\n                    >\n            Stiftungsfonds von Stiftern: Verm\u00f6genspoolings-Fonds        <\/h3>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Verm\u00f6genspooling-Fonds gehen \u00fcber die bereits genannten Kriterien hinaus. Es handelt sich bei ihnen um Fonds, die nicht nur f\u00fcr Stifter, sondern auch von Stiftern konzipiert wurden. Der Initiator ist ebenfalls ein Sozialunternehmen und kein Finanzinstitut, aber es arbeiten trotzdem ausgew\u00e4hlte Finanzprofis transparent mit den Anlagesummen. Anders als bei herk\u00f6mmlichen Fonds begutachtet ein externer und neutraler Verm\u00f6gensbeirat aus der Stifter- und Finanzszene ihre Leistung. Anleger haben so also den Vorteil der doppelten Kontrolle.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n<div class=\"container container--narrow \" >\n    <div class=\"link-list box\">\n                    <h2 class=\"headline headline--h3\">\n                Das k\u00f6nnte Sie auch interessieren:            <\/h2>\n                            <ul class=\"link-list__list\">\n                                    <li class=\"link-list__item\">\n                        <a class=\"link link--arrow-right\" href=\"https:\/\/www.finanzen.net\/ratgeber\/mischfonds-kaufen\/\" target=\"_blank\">\n                            Mischfonds                        <\/a>\n                    <\/li>\n                                    <li class=\"link-list__item\">\n                        <a class=\"link link--arrow-right\" href=\"https:\/\/www.finanzen.net\/ratgeber\/geldmarktfonds\/\" target=\"_blank\">\n                            Geldmarktfonds                        <\/a>\n                    <\/li>\n                                    <li class=\"link-list__item\">\n                        <a class=\"link link--arrow-right\" href=\"https:\/\/www.finanzen.net\/ratgeber\/fondsgebundene-lebensversicherung\/\" target=\"_blank\">\n                            Fondsgebundene Lebensversicherung                        <\/a>\n                    <\/li>\n                                    <li class=\"link-list__item\">\n                        <a class=\"link link--arrow-right\" href=\"https:\/\/www.finanzen.net\/ratgeber\/fondsarten\/\" target=\"_blank\">\n                            Fondsarten                        <\/a>\n                    <\/li>\n                                    <li class=\"link-list__item\">\n                        <a class=\"link link--arrow-right\" href=\"https:\/\/www.finanzen.net\/ratgeber\/multi-asset-fonds-kaufen\/\" target=\"_blank\">\n                            Multi Asset Fonds                        <\/a>\n                    <\/li>\n                                    <li class=\"link-list__item\">\n                        <a class=\"link link--arrow-right\" href=\"https:\/\/www.finanzen.net\/ratgeber\/dividendenfonds-kaufen\/\" target=\"_blank\">\n                            Dividendenfonds                        <\/a>\n                    <\/li>\n                            <\/ul>\n            <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow js-is-toc\" id=\"stiftungsfonds-vergleich\" >\n                <h2            class=\"headline headline--h2\"\n                    >\n            Stiftungsfonds-Vergleich: Die besten Stiftungsfonds        <\/h2>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Bei den untersuchten Fonds handelt es sich \u00fcberwiegend um Mischfonds mit defensivem Charakter. In die Bewertung der Fonds flossen qualitative Kriterien wie Fondsmanagement, KVG, Anlagegrunds\u00e4tze inklusive Portfolio sowie Risikomanagement, Aussch\u00fcttungsrendite und Kosten ein. In der quantitativen Analyse wurden Return, Sharpe Ratio, Volatilit\u00e4t und maximaler Verlust analysiert und so das jeweilige Risiko-Rendite-Verh\u00e4ltnis bewertet.<\/p>\n<p>In der abschlie\u00dfenden Gesamtbewertung wurden die Ergebnisse der qualitativen und quantitativen Analyse zusammengef\u00fchrt. Bei den Fonds handelt es sich um speziell f\u00fcr Stiftungen vertriebene Publikumsfonds. Sie verf\u00fcgen \u00fcber ein Volumen von mindestens 50 und eine Historie von mehr als drei Jahren.<\/p>\n<p><strong><span class=\"lightbulb-text\">Tipp:<\/span><\/strong>\u00a0Beim\u00a0<a title=\"Fondssparen: Mit Fondssparplan in die besten Investmentfonds investieren\" href=\"https:\/\/www.finanzen.net\/ratgeber\/wertpapiere\/fondssparen-mit-fondssparplan\">Fondssparen<\/a>\u00a0k\u00f6nnen Investoren mit einem langen Anlagehorizont bequem Verm\u00f6gen aufbauen, schauen Sie doch mal in unseren entsprechenden Ratgeber-Artikel rein.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow\" >\n                <h3            class=\"headline headline--h3\"\n                    >\n            Die besten Stiftungsfonds 2024        <\/h3>\n        <\/div>\n\n\n<div class=\"container container--narrow\" >\n            <h2 class=\"headline headline--h2\">\n            <small>Stand Juli 2024<\/small>        <\/h2>\n                            <div class=\"table-container\">\n        \n                <table class=\"table\">\n                                                                <thead>\n                            <tr>\n                                                                    <th>\n                                        Fondsname                                    <\/th>\n                                                                    <th>\n                                        WKN \/ ISIN                                    <\/th>\n                                                                    <th>\n                                        TER                                    <\/th>\n                                                                    <th>\n                                        5-Jahres-Performance                                    <\/th>\n                                                            <\/tr>\n                        <\/thead>\n                                                                <tbody>\n                                                            <tr>\n                                                                            <td>\n                                            <a title=\"BKC Treuhand Portfolio I Fonds\" href=\"https:\/\/www.finanzen.net\/fonds\/bkc-treuhand-portfolio-i-de000a0yfq92\" target=\"_blank\" rel=\"noopener\">BKC Treuhand Portfolio<\/a>                                        <\/td>\n                                                                            <td>\n                                            \tA0YFQ9 \/ DE000A0YFQ92                                        <\/td>\n                                                                            <td>\n                                            0,69 Prozent                                        <\/td>\n                                                                            <td>\n                                            +8,32 Prozent                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            <a title=\"Flossbach von Storch - Stiftung SI Fonds\" href=\"https:\/\/www.finanzen.net\/fonds\/flossbach-von-storch-stiftung-si-lu0323577766\" target=\"_blank\" rel=\"noopener\">FvS Stiftung<\/a>                                        <\/td>\n                                                                            <td>\n                                            A0M43S \/ LU0323577766                                        <\/td>\n                                                                            <td>\n                                            0,49 Prozent                                        <\/td>\n                                                                            <td>\n                                            +14,56 Prozent                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            <a title=\"DWS Stiftungsfonds LD Fonds\" href=\"https:\/\/www.finanzen.net\/fonds\/dws-stiftungsfonds-ld-de0005318406\" target=\"_blank\" rel=\"noopener\">DWS Stiftungsfonds<\/a>                                        <\/td>\n                                                                            <td>\n                                            A0M43S \/ LU0323577766                                        <\/td>\n                                                                            <td>\n                                            1,09 Prozent                                        <\/td>\n                                                                            <td>\n                                            +5,97 Prozent                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            <a title=\"SALytic Stiftungsfonds AMI I (a) Fonds\" href=\"https:\/\/www.finanzen.net\/fonds\/landert-stiftungsfonds-ami-i-a-de000a1wz0s9\" target=\"_blank\" rel=\"noopener\">SALytic Stiftungsfonds<\/a>                                        <\/td>\n                                                                            <td>\n                                            A1WZ0S \/ DE000A1WZ0S9                                        <\/td>\n                                                                            <td>\n                                            0,67 Prozent                                        <\/td>\n                                                                            <td>\n                                            +12,94 Prozent                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            <a title=\"Stiftungsfonds Spiekermann &amp; CO Fonds\" href=\"https:\/\/www.finanzen.net\/fonds\/stiftungsfonds-spiekermann-co-de000a1c1qh0\" target=\"_blank\" rel=\"noopener\">Stiftungsfonds Spiekermann &amp; Co.<\/a>                                        <\/td>\n                                                                            <td>\n                                            A1C1QH \/ ISIN: DE000A1C1QH0                                        <\/td>\n                                                                            <td>\n                                            0,98 Prozent                                        <\/td>\n                                                                            <td>\n                                            +12,03 Prozent                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            <a title=\"Bethmann Stiftungsfonds P Fonds\" href=\"https:\/\/www.finanzen.net\/fonds\/bethmann-stiftungsfonds-p-de000dws08y8\" target=\"_blank\" rel=\"noopener\">Bethmann Stiftungsfonds<\/a>                                        <\/td>\n                                                                            <td>\n                                            DWS08Y \/ DE000DWS08Y8                                        <\/td>\n                                                                            <td>\n                                            0,82 Prozent                                        <\/td>\n                                                                            <td>\n                                            +4,32 Prozent                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            <a title=\"MEAG FairReturn A Fonds\" href=\"https:\/\/www.finanzen.net\/fonds\/meag-fairreturn-a-de000a0rfj25\" target=\"_blank\" rel=\"noopener\">MEAG FairReturn<\/a>                                        <\/td>\n                                                                            <td>\n                                            \tA0RFJ2 \/ DE000A0RFJ25                                        <\/td>\n                                                                            <td>\n                                            0,94 Prozent                                        <\/td>\n                                                                            <td>\n                                            -0,05 Prozent                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            <a title=\"Nordlux Pro Fondsmanagement - StiftungsPartner A Fonds\" href=\"https:\/\/www.finanzen.net\/fonds\/nordlux-pro-fondsmanagement-stiftungspartner-a-lu1297767904\" target=\"_blank\" rel=\"noopener\">Nordlux Stiftungspartner<\/a>                                        <\/td>\n                                                                            <td>\n                                            A14038 \/ LU1297767904                                        <\/td>\n                                                                            <td>\n                                            1,24 Prozent                                        <\/td>\n                                                                            <td>\n                                            +3,36 Prozent                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            <a title=\"Prisma Aktiv UI - R Fonds\" href=\"https:\/\/www.finanzen.net\/fonds\/prisma-aktiv-ui-r-de000a1w9a77\" target=\"_blank\" rel=\"noopener\">Prisma Aktiv<\/a>                                        <\/td>\n                                                                            <td>\n                                            A1W9A7 \/ DE000A1W9A77                                        <\/td>\n                                                                            <td>\n                                            1,59 Prozent                                        <\/td>\n                                                                            <td>\n                                            +13,39 Prozent                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            <a title=\"CSR Ertrag Plus Fonds\" href=\"https:\/\/www.finanzen.net\/fonds\/csr-ertrag-plus-de000a2p37p4\" target=\"_blank\" rel=\"noopener\">CSR Ertrag Plus<\/a>                                        <\/td>\n                                                                            <td>\n                                            A2P37P \/ DE000A2P37P4                                        <\/td>\n                                                                            <td>\n                                            0,65 Prozent                                        <\/td>\n                                                                            <td>\n                                            -2,27 Prozent                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            <a title=\"Fonds f\u00fcr Stiftungen Invesco Fonds\" href=\"https:\/\/www.finanzen.net\/fonds\/fonds-fuer-stiftungen-invesco-de0008023565\" target=\"_blank\" rel=\"noopener\">Fonds f\u00fcr Stiftungen Invesco<\/a>                                        <\/td>\n                                                                            <td>\n                                            802356 \/ DE0008023565                                        <\/td>\n                                                                            <td>\n                                            1,32 Prozent                                        <\/td>\n                                                                            <td>\n                                            +16,72 Prozent                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            <a title=\"FOS Rendite und Nachhaltigkeit A Fonds\" href=\"https:\/\/www.finanzen.net\/fonds\/fos-rendite-und-nachhaltigkeit-a-de000dws0xf8\" target=\"_blank\" rel=\"noopener\">FOS Rendite und Nachhaltigkeit<\/a>                                        <\/td>\n                                                                            <td>\n                                            DWS0XF \/ DE000DWS0XF8                                        <\/td>\n                                                                            <td>\n                                            0,90 Prozent                                        <\/td>\n                                                                            <td>\n                                            +13,34 Prozent                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            <a title=\"Berenberg 1590 Stiftung A Fonds\" href=\"https:\/\/www.finanzen.net\/fonds\/berenberg-1590-stiftung-a-de000a0re972\" target=\"_blank\" rel=\"noopener\">Berenberg-1590-Stiftung<\/a>                                        <\/td>\n                                                                            <td>\n                                            \tA0RE97 \/ DE000A0RE972                                        <\/td>\n                                                                            <td>\n                                            1,16 Prozent                                        <\/td>\n                                                                            <td>\n                                            +6,75 Prozent                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            <a title=\"HAL Nachhaltigkeitsfonds Stiftungen IA Fonds\" href=\"https:\/\/www.finanzen.net\/fonds\/lam-stifterfonds-universal-r-de000a0jeln1\" target=\"_blank\" rel=\"noopener\">HAL Nachhaltigkeitsfonds Stiftungen<\/a>                                        <\/td>\n                                                                            <td>\n                                            A0JELN \/ DE000A0JELN1                                        <\/td>\n                                                                            <td>\n                                            0,63 Prozent                                        <\/td>\n                                                                            <td>\n                                            +4,53 Prozent                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            <a title=\"Sarasin-FairInvest-Universal-Fonds A Fonds\" href=\"https:\/\/www.finanzen.net\/fonds\/sarasin-fairinvest-universal-fonds-a-de000a0mqr01\" target=\"_blank\" rel=\"noopener\">Sarasin-FairInvest-Universal-Fonds<\/a>                                        <\/td>\n                                                                            <td>\n                                            A0MQR0 \/ DE000A0MQR01                                        <\/td>\n                                                                            <td>\n                                            1,33 Prozent                                        <\/td>\n                                                                            <td>\n                                            -2,81 Prozent                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            <a title=\"Allianz Stiftungsfds Nachhaltigk A Fonds\" href=\"https:\/\/www.finanzen.net\/fonds\/allianz-stiftungsfds-nachhaltigk-a-lu0224473941\" target=\"_blank\" rel=\"noopener\">Allianz Stiftungsfonds Nachhaltigkeit<\/a>                                        <\/td>\n                                                                            <td>\n                                            A0F416 \/ LU0224473941\t                                        <\/td>\n                                                                            <td>\n                                            1,20 Prozent                                        <\/td>\n                                                                            <td>\n                                            -3,86 Prozent                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            <a title=\"Frankfurter Aktienfonds f\u00fcr Stiftungen T Fonds\" href=\"https:\/\/www.finanzen.net\/fonds\/frankfurter-aktienfonds-fuer-stiftungen-t-de000a0m8hd2\" target=\"_blank\" rel=\"noopener\">Frankfurter Aktienfonds f\u00fcr Stiftungen<\/a>                                        <\/td>\n                                                                            <td>\n                                            A0M8HD \/ DE000A0M8HD2                                        <\/td>\n                                                                            <td>\n                                            1,31 Prozent                                        <\/td>\n                                                                            <td>\n                                            +21,00 Prozent                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            <a title=\"Deka-Stiftungen Balance CF Fonds\" href=\"https:\/\/www.finanzen.net\/fonds\/deka-stiftungen-balance-cf-de0005896864\" target=\"_blank\" rel=\"noopener\">Deka-Stiftungen Balance<\/a>                                        <\/td>\n                                                                            <td>\n                                            589686 \/ DE0005896864\t                                        <\/td>\n                                                                            <td>\n                                            1,17 Prozent                                        <\/td>\n                                                                            <td>\n                                            +4,97 Prozent                                        <\/td>\n                                                                    <\/tr>\n                                                    <\/tbody>\n                                    <\/table>\n                    <\/div>\n            <\/div>\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"youtube-channel-teaser box\">\n                    <a class=\"youtube-channel-teaser__image-container\" href=\"https:\/\/www.youtube.com\/channel\/UCxD5ug_M184KrXgPj9v7qeA\" target=\"_blank\">\n                <img decoding=\"async\" src=\"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2023\/10\/icon-youtube.svg\">\n            <\/a>\n                            <div class=\"box__content flow-content\">\n                <p><strong>Du willst noch mehr Finanzwissen schnell erkl\u00e4rt?<\/strong><br \/>\n<a href=\"https:\/\/www.youtube.com\/channel\/UCxD5ug_M184KrXgPj9v7qeA\" target=\"_blank\" rel=\"noopener\">Dann abonniere jetzt unseren YouTube-Kanal!<\/a> Wir produzieren regelm\u00e4\u00dfig neue <strong>Ratgeber-Videos<\/strong> rund um die Themen B\u00f6rse, Geldanlage und Finanzen. Als Abonnent wirst du sofort informiert, wenn ein neues Erkl\u00e4rvideo erscheint &#8211; so verpasst du nichts mehr!<\/p>\n            <\/div>\n            <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow js-is-toc\" id=\"Fazit-Diese-Stfitungsfonds-schnitten-am-besten-ab\" >\n                <h2            class=\"headline headline--h2\"\n                    >\n            Fazit: Diese Stfitungsfonds schnitten am besten ab        <\/h2>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Das Ergebnis: Die beste Performance legten der Frankfurter Aktiensfonds sowie der Fonds von Invesco ab. Allerdings geh\u00f6ren beide mit einer TER von \u00fcber 1,3 Prozent auch mit zu den teuersten Investments im Vergleich. Der g\u00fcnstigste Fonds von FvS (Flossbach von Storch) schneidet mit einer Performance von 14,56 Prozent bei einer TER von 0,49 Prozent auch sehr gut ab.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow\" >\n                <h3            class=\"headline headline--h3\"\n                    >\n            Frankfurter Aktienfonds f\u00fcr Stiftungen T Fonds        <\/h3>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Die Anlagestrategie des Frankfurter Aktienfonds (WKN: A0M8HD \/ ISIN: DE000A0M8HD2) leitet sich aus den vier bew\u00e4hrten Prinzipien des Value-Investing ab: Investiert wird nach einer fundamental orientierten bottom-up Analyse mit Makro-Overlay in eigent\u00fcmergef\u00fchrte Aktien mit Sicherheitsmarge und wirtschaftlichem Burggraben, wobei zus\u00e4tzlich auf Gesamtportfolio Ebene ein Makrooverlay etabliert ist, um so das Risiko f\u00fcr die Anleger zu reduzieren und gleichzeitig die Renditechancen zu erhalten. Bestehen keine regionalen Beschr\u00e4nkungen bei der Auswahl der nachhaltigen Valueaktien, der Fonds hat jedoch einen regionalen Schwerpunkt im deutschsprachigen Europa. Der Fonds dient der langfristigen Erhaltung und dem Aufbau des Verm\u00f6gens seiner Investoren. Bei der Auswahl der Zielfonds und Wertpapiere werden dar\u00fcber hinaus ESG-Kriterien wie folgt ber\u00fccksichtigt: Mindestens 51 Prozent des Wertes des OGAW-Sonderverm\u00f6gens werden in ESG-konforme Investments angelegt, welche durch Ausschlusskriterien und unter Einbezug von ESG-Merkmalen bestimmt werden. Bis auf die Assets (83 Prozent in Aktien) ist der Fonds stark in verschiedene Erdregionen und Branchen diversifiziert.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow\" >\n                <h3            class=\"headline headline--h3\"\n                    >\n            Fonds f\u00fcr Stiftungen Invesco        <\/h3>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Der Invesco-Fonds (WKN: 802356 \/ ISIN: DE0008023565) legt weltweit gemischt in Aktien und verzinslichen Wertpapieren gem\u00e4\u00df \u00a7 193 KAGB an. Das OGAW-Sonderverm\u00f6gen setzt sich zu mindestens 51 Prozent aus verzinslichen Wertpapieren, Geldmarktinstrumenten oder Bankguthaben zusammen. Aktien- und Rentenanteile werden im Rahmen der \u201eTaktischen-Asset-Allocation\u201c laufend auf ihre relative Attraktivit\u00e4t \u00fcberpr\u00fcft und in Abstimmung mit dem Anlageausschuss ggf. ge\u00e4nderten Marktsituationen angepasst. Der Erwerb von Aktien und Aktienindexzertifikaten ist bis zu 49 Prozent des Wertes des OGAW-Sonderverm\u00f6gens zul\u00e4ssig. Bei der Zusammensetzung des Anlageuniversums flie\u00dfen ethische und nachhaltige Wertvorstellungen ein. Deshalb werden neben dem notwendigen finanzwirtschaftlichen Analyseprozess auch nachhaltige, \u00f6kologische und soziale Kriterien ber\u00fccksichtigt.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow\" >\n                <h3            class=\"headline headline--h3\"\n                    >\n            Flossbach von Storch &#8211; Foundation Defensive &#8211; SI Fonds        <\/h3>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Ziel der Anlagepolitik des Flossbach von Storch \u2013 Stiftung (\u201eTeilfonds\u201c) ist es, unter Ber\u00fccksichtigung des Anlageri-sikos einen angemessenen Wertzuwachs in der Teilfondsw\u00e4hrung zu erzielen. Die Anlagestrategie wird auf Basis der fundamentalen Analyse der globalen Finanzm\u00e4rkte getroffen. Weiterhin sollen die Anlagen nach den Kriterien der Werthaltigkeit (Value) ausgew\u00e4hlt werden. <strong>Der Teilfonds ist ausschlie\u00dflich erwerbbar und haltef\u00e4hig f\u00fcr eine unter \u201eAnteilklassen des Teilfonds\u201c spezifizierte Anlegerschaft. Anderen Anlegern sind der Erwerb sowie das Halten von Anteilen des Teilfonds nicht gestattet.<\/strong><\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow js-is-toc\" id=\"Stiftungsfonds--das-sollten-Sie-tun\" >\n                <h2            class=\"headline headline--h2\"\n                    >\n            Stiftungsfonds &#8211; das sollten Sie tun        <\/h2>\n        <\/div>\n\n\n\n<div class=\"container container--narrow \" >\n            <ol class=\"ordered-list ordered-list--type1\">\n                           <li class=\"ordered-list__item\">\n                    <div class=\"ordered-list__content\">\n                                                                            <div class=\"ordered-list__text\">\n                                <p>Wollen Sie in Dachfonds investieren, dann er\u00f6ffnen Sie zun\u00e4chst ein Wertpapierdepot. Bei der Suche nach dem passenden Anbieter hilft Ihnen unser\u00a0<a title=\"Online-Broker-Vergleich\" href=\"https:\/\/www.finanzen.net\/online-broker-vergleich\/\">Online-Broker-Vergleich<\/a>.<\/p>\n                            <\/div>\n                                            <\/div>\n                <\/li>\n                            <li class=\"ordered-list__item\">\n                    <div class=\"ordered-list__content\">\n                                                                            <div class=\"ordered-list__text\">\n                                <p>Entscheiden Sie \u00fcber die Zielsetzung Ihres Investments.<\/p>\n                            <\/div>\n                                            <\/div>\n                <\/li>\n                            <li class=\"ordered-list__item\">\n                    <div class=\"ordered-list__content\">\n                                                                            <div class=\"ordered-list__text\">\n                                <p>W\u00e4hlen Sie einen f\u00fcr Ihre\u00a0<a title=\"Anlagestrategien\" href=\"https:\/\/www.finanzen.net\/ratgeber\/anlagestrategien\">Anlagestrategie<\/a>\u00a0passenden Stiftungsfonds aus.<\/p>\n                            <\/div>\n                                            <\/div>\n                <\/li>\n                            <li class=\"ordered-list__item\">\n                    <div class=\"ordered-list__content\">\n                                                                            <div class=\"ordered-list__text\">\n                                <p>Nachdem Sie Ihre Wahl getroffen haben, k\u00f6nnen Sie in den entsprechenden Fonds investieren.<\/p>\n                            <\/div>\n                                            <\/div>\n                <\/li>\n                    <\/ol>\n    <\/div>\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"disclaimer flow-content\">\n                    <small>\n                <p style=\"font-size: 11pt;\">Disclaimer: Die in diesem Artikel enthaltenen Inhalte dienen ausschlie\u00dflich allgemeinen Informations-, Bildungs- und Marketingzwecken ohne Gew\u00e4hr auf Vollst\u00e4ndigkeit, Richtigkeit und Aktualit\u00e4t. Die Inhalte stellen keine Anlageberatung, Anlagestrategieempfehlung oder Aufforderung zum Kauf oder Verkauf von Wertpapieren oder sonstigen Finanzinstrumenten dar. Die Informationen ber\u00fccksichtigen nicht die individuellen Anlageziele und finanzielle Situation des Lesers. Jede Anlageentscheidung sollte eigenverantwortlich getroffen und sorgf\u00e4ltig gepr\u00fcft werden. Vor einer Anlageentscheidung sollte der Rat eines Anlage- und Steuerberaters eingeholt werden. Der Handel mit Wertpapieren oder sonstigen Finanzinstrumenten ist mit hohen Risiken verbunden, bis hin zum Totalverlust des eingesetzten Kapitals. Die in der Vergangenheit erzielte Performance ist kein Indikator f\u00fcr zuk\u00fcnftige Wertentwicklungen. Aussagen \u00fcber zuk\u00fcnftige wirtschaftliche Entwicklungen basieren grunds\u00e4tzlich auf Annahmen und Einsch\u00e4tzungen, die sich im Zeitablauf als nicht zutreffend erweisen k\u00f6nnen. Wir \u00fcbernehmen keine Haftung f\u00fcr Verluste, die durch die Umsetzung der in diesem Artikel genannten Informationen entstehen.<\/p>\n<p style=\"font-size: 11pt;\"><sup>1<\/sup>Hinweis zu ZERO: <a href=\"https:\/\/www.finanzen.net\/zero\/?utm_source=finnet-ratgeber&amp;utm_medium=web&amp;utm_term=fnet_017m&amp;utm_campaign=content&amp;utm_content=[current_slug]\" target=\"_blank\" rel=\"noopener\">finanzen.net zero<\/a> ist ein Angebot der <a href=\"https:\/\/www.finanzen.net\/zero\/impressum\/?utm_source=finnet-ratgeber&amp;utm_medium=web&amp;utm_term=fnet_017m&amp;utm_campaign=content&amp;utm_content=[current_slug]\" target=\"_blank\" rel=\"noopener\">finanzen.net zero GmbH<\/a>, einer Tochter der <a href=\"https:\/\/www.finanzen.net\/impressum\">finanzen.net GmbH<\/a>.<\/p>\n<p style=\"font-size: 11pt;\"><sup>*<\/sup>Hinweis zu Affiliate-Links: Unsere Ratgeber-Artikel sind objektiv und unabh\u00e4ngig erstellt, wobei mit Sternchen gekennzeichnete Links zur Finanzierung der kostenlosen Inhalte dienen. Die Verg\u00fctung aus diesen Links hat keinen Einfluss auf unsere Inhalte.<\/p>\n            <\/small>\n                    <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Stiftungsfonds sind Investmentfonds, die explizit f\u00fcr Stiftungen aufgelegt werden.\u00a0Wir verraten, welche Stiftungsfonds sich lohnen, wie Anleger Stiftungsfonds kaufen k\u00f6nnen und worauf sie dabei achten m\u00fcssen. In unserem Stiftungsfonds-Vergleich stellen wir die besten Stiftungsfonds f\u00fcr Sie vor. Gleich zu Beginn gibt&#8217;s die besten Empfehlungen und Tipps.<\/p>\n","protected":false},"author":16,"featured_media":3773,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1421],"tags":[],"class_list":["post-1583","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-produkte-vergleiche"],"acf":[],"yoast_head":"<title>Stiftungsfonds-Vergleich: So investieren Anleger in die besten Stiftungsfonds - Finanzen.net Ratgeber: Finanzwissen, das dich weiterbringt<\/title>\n<meta name=\"description\" content=\"Stiftungsfonds-Vergleich: Das sind die besten Stiftungsfonds und so investieren Anleger in diese Mischfonds mit defensiver Ausrichtung.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.finanzen.net\/ratgeber\/fonds\/produkte-vergleiche\/stiftungsfonds-vergleich\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stiftungsfonds-Vergleich: So investieren Anleger in die besten Stiftungsfonds - Finanzen.net Ratgeber: Finanzwissen, das dich weiterbringt\" \/>\n<meta property=\"og:description\" content=\"Stiftungsfonds-Vergleich: Das sind die besten Stiftungsfonds und so investieren Anleger in diese Mischfonds mit defensiver Ausrichtung.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.finanzen.net\/ratgeber\/fonds\/produkte-vergleiche\/stiftungsfonds-vergleich\/\" \/>\n<meta property=\"og:site_name\" content=\"Finanzen.net Ratgeber: Finanzwissen, das dich weiterbringt\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-02T22:39:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-19T16:59:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/shutterstock_2299627889-PhotoRoom.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"882\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redaktion Ratgeber\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redaktion Ratgeber\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>","yoast_head_json":{"title":"Stiftungsfonds-Vergleich: So investieren Anleger in die besten Stiftungsfonds - Finanzen.net Ratgeber: Finanzwissen, das dich weiterbringt","description":"Stiftungsfonds-Vergleich: Das sind die besten Stiftungsfonds und so investieren Anleger in diese Mischfonds mit defensiver Ausrichtung.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.finanzen.net\/ratgeber\/fonds\/produkte-vergleiche\/stiftungsfonds-vergleich\/","og_locale":"de_DE","og_type":"article","og_title":"Stiftungsfonds-Vergleich: So investieren Anleger in die besten Stiftungsfonds - Finanzen.net Ratgeber: Finanzwissen, das dich weiterbringt","og_description":"Stiftungsfonds-Vergleich: Das sind die besten Stiftungsfonds und so investieren Anleger in diese Mischfonds mit defensiver Ausrichtung.","og_url":"https:\/\/www.finanzen.net\/ratgeber\/fonds\/produkte-vergleiche\/stiftungsfonds-vergleich\/","og_site_name":"Finanzen.net Ratgeber: Finanzwissen, das dich weiterbringt","article_published_time":"2020-12-02T22:39:18+00:00","article_modified_time":"2026-05-19T16:59:41+00:00","og_image":[{"width":1920,"height":882,"url":"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/shutterstock_2299627889-PhotoRoom.jpg","type":"image\/jpeg"}],"author":"Redaktion Ratgeber","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"Redaktion Ratgeber","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.finanzen.net\/ratgeber\/fonds\/produkte-vergleiche\/stiftungsfonds-vergleich\/#article","isPartOf":{"@id":"https:\/\/www.finanzen.net\/ratgeber\/fonds\/produkte-vergleiche\/stiftungsfonds-vergleich\/"},"author":{"name":"Redaktion Ratgeber","@id":"https:\/\/www.finanzen.net\/ratgeber\/#\/schema\/person\/7de2b54939f007854918b2e05989b109"},"headline":"Stiftungsfonds","datePublished":"2020-12-02T22:39:18+00:00","dateModified":"2026-05-19T16:59:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.finanzen.net\/ratgeber\/fonds\/produkte-vergleiche\/stiftungsfonds-vergleich\/"},"wordCount":1684,"image":{"@id":"https:\/\/www.finanzen.net\/ratgeber\/fonds\/produkte-vergleiche\/stiftungsfonds-vergleich\/#primaryimage"},"thumbnailUrl":"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/shutterstock_2299627889-PhotoRoom.jpg","articleSection":["Produkte &amp; Vergleiche"],"inLanguage":"de"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.finanzen.net\/ratgeber\/fonds\/produkte-vergleiche\/stiftungsfonds-vergleich\/","url":"https:\/\/www.finanzen.net\/ratgeber\/fonds\/produkte-vergleiche\/stiftungsfonds-vergleich\/","name":"Stiftungsfonds-Vergleich: So investieren Anleger in die besten Stiftungsfonds - Finanzen.net Ratgeber: Finanzwissen, das dich weiterbringt","isPartOf":{"@id":"https:\/\/www.finanzen.net\/ratgeber\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.finanzen.net\/ratgeber\/fonds\/produkte-vergleiche\/stiftungsfonds-vergleich\/#primaryimage"},"image":{"@id":"https:\/\/www.finanzen.net\/ratgeber\/fonds\/produkte-vergleiche\/stiftungsfonds-vergleich\/#primaryimage"},"thumbnailUrl":"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/shutterstock_2299627889-PhotoRoom.jpg","datePublished":"2020-12-02T22:39:18+00:00","dateModified":"2026-05-19T16:59:41+00:00","author":{"@id":"https:\/\/www.finanzen.net\/ratgeber\/#\/schema\/person\/7de2b54939f007854918b2e05989b109"},"description":"Stiftungsfonds-Vergleich: Das sind die besten Stiftungsfonds und so investieren Anleger in diese Mischfonds mit defensiver Ausrichtung.","breadcrumb":{"@id":"https:\/\/www.finanzen.net\/ratgeber\/fonds\/produkte-vergleiche\/stiftungsfonds-vergleich\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.finanzen.net\/ratgeber\/fonds\/produkte-vergleiche\/stiftungsfonds-vergleich\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.finanzen.net\/ratgeber\/fonds\/produkte-vergleiche\/stiftungsfonds-vergleich\/#primaryimage","url":"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/shutterstock_2299627889-PhotoRoom.jpg","contentUrl":"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/shutterstock_2299627889-PhotoRoom.jpg","width":1920,"height":882},{"@type":"BreadcrumbList","@id":"https:\/\/www.finanzen.net\/ratgeber\/fonds\/produkte-vergleiche\/stiftungsfonds-vergleich\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.finanzen.net\/ratgeber\/"},{"@type":"ListItem","position":2,"name":"Fonds","item":"https:\/\/www.finanzen.net\/ratgeber\/.\/fonds\/"},{"@type":"ListItem","position":3,"name":"Produkte &amp; Vergleiche","item":"https:\/\/www.finanzen.net\/ratgeber\/.\/fonds\/produkte-vergleiche\/"},{"@type":"ListItem","position":4,"name":"Stiftungsfonds"}]},{"@type":"WebSite","@id":"https:\/\/www.finanzen.net\/ratgeber\/#website","url":"https:\/\/www.finanzen.net\/ratgeber\/","name":"Finanzen.net Ratgeber - Die Ganze Welt der Finanzen","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.finanzen.net\/ratgeber\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.finanzen.net\/ratgeber\/#\/schema\/person\/7de2b54939f007854918b2e05989b109","name":"Redaktion Ratgeber","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/image-6-150x150.png","url":"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/image-6-150x150.png","contentUrl":"https:\/\/www.finanzen.net\/ratgeber\/wp-content\/uploads\/2024\/01\/image-6-150x150.png","caption":"Redaktion Ratgeber"},"url":"https:\/\/www.finanzen.net\/ratgeber\/author\/team-ratgeber\/"}]}},"_links":{"self":[{"href":"https:\/\/www.finanzen.net\/ratgeber\/wp-json\/wp\/v2\/posts\/1583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.finanzen.net\/ratgeber\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.finanzen.net\/ratgeber\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.finanzen.net\/ratgeber\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.finanzen.net\/ratgeber\/wp-json\/wp\/v2\/comments?post=1583"}],"version-history":[{"count":8,"href":"https:\/\/www.finanzen.net\/ratgeber\/wp-json\/wp\/v2\/posts\/1583\/revisions"}],"predecessor-version":[{"id":39506,"href":"https:\/\/www.finanzen.net\/ratgeber\/wp-json\/wp\/v2\/posts\/1583\/revisions\/39506"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.finanzen.net\/ratgeber\/wp-json\/wp\/v2\/media\/3773"}],"wp:attachment":[{"href":"https:\/\/www.finanzen.net\/ratgeber\/wp-json\/wp\/v2\/media?parent=1583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.finanzen.net\/ratgeber\/wp-json\/wp\/v2\/categories?post=1583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.finanzen.net\/ratgeber\/wp-json\/wp\/v2\/tags?post=1583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}